{"id":2403,"date":"2011-09-08T08:39:25","date_gmt":"2011-09-08T07:39:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2403"},"modified":"2011-09-08T08:39:25","modified_gmt":"2011-09-08T07:39:25","slug":"los-viticultores-protestan-manana-ante-el-consejo-regulador-del-rioja-por-los-bajos-pagos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/08\/los-viticultores-protestan-manana-ante-el-consejo-regulador-del-rioja-por-los-bajos-pagos\/","title":{"rendered":"Los viticultores protestan ma\u00f1ana ante el Consejo Regulador del Rioja por los bajos pagos"},"content":{"rendered":"<h5><\/h5>\n<h5><span style=\"color: #008000\">\u00c1lava<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2404\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog.jpg\" alt=\"\" width=\"600\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog-768x194.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/8-9-11blog-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Los agricultores de la denominaci\u00f3n rioja unir\u00e1n sus fuerzas ma\u00f1ana frente a la sede del Consejo Regulador para exigir \u00abprecios dignos\u00bb para sus uvas. Sumidos en una situaci\u00f3n \u00abmuy cr\u00edtica\u00bb por los bajos pagos que percibieron las dos \u00faltimas campa\u00f1as, los viticultores se movilizar\u00e1n por cuarta vez en a\u00f1o y medio para luchar por que sus vi\u00f1edos vuelvan a ser rentables. <a href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110908\/alava\/viticultores-protestan-manana-ante-20110908.html\" rel=\"external nofollow\">(+)<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00c1lava Los agricultores de la denominaci\u00f3n rioja unir\u00e1n sus fuerzas ma\u00f1ana frente a la sede del Consejo Regulador para exigir \u00abprecios dignos\u00bb para sus uvas. Sumidos en una situaci\u00f3n \u00abmuy cr\u00edtica\u00bb por los bajos pagos que percibieron las dos \u00faltimas campa\u00f1as, los viticultores se movilizar\u00e1n por cuarta vez en a\u00f1o y medio para luchar por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[983,985,5598,7104,7170,7270,7299],"class_list":["post-2403","post","type-post","status-publish","format-standard","hentry","category-tiras-de-alava","tag-bodega","tag-bodegueros","tag-precio","tag-uva","tag-vendimia","tag-vino","tag-viticultores"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}