{"id":2368,"date":"2011-09-04T09:54:13","date_gmt":"2011-09-04T08:54:13","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2368"},"modified":"2011-09-04T09:54:13","modified_gmt":"2011-09-04T08:54:13","slug":"pasion-por-el-coleccionismo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/09\/04\/pasion-por-el-coleccionismo\/","title":{"rendered":"Pasi\u00f3n por el coleccionismo"},"content":{"rendered":"<h5><span style=\"color: #0000ff\">Miranda<\/span><\/h5>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2369\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog.jpg\" alt=\"\" width=\"602\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog.jpg 1171w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog-768x193.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/09\/mir4-9-11blog-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/p>\n<p>Suelen empezar por casualidad. Nadie se plantea, de partida, empezar a coleccionar nada. Siempre hay en medio un desencadenante, un hecho casual, que hace que muchos se animen a sumar ejemplares, modelos, piezas similares o con algo en com\u00fan y, cuyo valor, en la mayor\u00eda de las ocasiones es m\u00e1s sentimental que econ\u00f3mico&#8230; (+)<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Miranda Suelen empezar por casualidad. Nadie se plantea, de partida, empezar a coleccionar nada. Siempre hay en medio un desencadenante, un hecho casual, que hace que muchos se animen a sumar ejemplares, modelos, piezas similares o con algo en com\u00fan y, cuyo valor, en la mayor\u00eda de las ocasiones es m\u00e1s sentimental que econ\u00f3mico&#8230; (+)<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[1676,1976,2736,7133],"class_list":["post-2368","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-coleccionismo","tag-cosas","tag-entretenimiento","tag-valor"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2368"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2368\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}