{"id":2302,"date":"2011-08-19T09:58:33","date_gmt":"2011-08-19T08:58:33","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2302"},"modified":"2011-08-19T09:58:33","modified_gmt":"2011-08-19T08:58:33","slug":"pasion-por-el-festval","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/08\/19\/pasion-por-el-festval\/","title":{"rendered":"Pasi\u00f3n por el FesTVal"},"content":{"rendered":"<p><span style=\"color: #008000\">\u00c1lava<\/span><\/p>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2303\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog.jpg\" alt=\"\" width=\"600\" height=\"151\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog-300x76.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog-768x194.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2011\/08\/19-8-11blog-1024x258.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\u00abPor fin tenemos las entradas para la inauguraci\u00f3n, \u00a1qu\u00e9 ganas de ver a Mario Casas y al resto de los actores de &#8216;El Barco&#8217;!\u00bb. Muy sonrientes, Miren y las dos Ane muestran los pases que acaban de comprar en la sede que el FesTVal tiene en la oficina de Turismo. Estas chicas de 13 y 14 a\u00f1os son ya unas veteranas de este festival.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00c1lava \u00abPor fin tenemos las entradas para la inauguraci\u00f3n, \u00a1qu\u00e9 ganas de ver a Mario Casas y al resto de los actores de &#8216;El Barco&#8217;!\u00bb. Muy sonrientes, Miren y las dos Ane muestran los pases que acaban de comprar en la sede que el FesTVal tiene en la oficina de Turismo. Estas chicas de 13 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3115,3122,4972,6741],"class_list":["post-2302","post","type-post","status-publish","format-standard","hentry","category-tiras-de-alava","tag-festival","tag-festval","tag-oficina","tag-television"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2302"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2302\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}