{"id":2165,"date":"2011-07-15T09:25:00","date_gmt":"2011-07-15T09:25:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=2164"},"modified":"2011-07-15T09:25:00","modified_gmt":"2011-07-15T09:25:00","slug":"la-antigua-estacion-del-ferrocarril-afronta-su-reforma-mas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2011\/07\/15\/la-antigua-estacion-del-ferrocarril-afronta-su-reforma-mas\/","title":{"rendered":"La antigua estaci\u00f3n del ferrocarril afronta su reforma m\u00e1s importante en 140 a\u00f1os"},"content":{"rendered":"<p><span style=\"color:#3333FF\">Miranda<br \/>\n<\/span><IMG src=\"\/inakicerrajeria\/files\/258552_mir14-7-11blog.jpg\" id=\"img_0\" class=\"imgizqda\" height=\"153\" width=\"600\"><br \/>\nEl entorno de la plaza de la Estaci\u00f3n afronta la \u00faltima fase de una  reforma global que arranc\u00f3 hace ya tres a\u00f1os con la terminal de  autobuses; ha continuado con el redise\u00f1o de la propia plaza; y est\u00e1  centrada en estos momentos en la recuperaci\u00f3n de un lugar clave: el  viejo centro de recepci\u00f3n de pasajeros. <A href=\"http:\/\/www.elcorreo.com\/alava\/v\/20110715\/miranda\/antigua-estacion-ferrocarril-afronta-20110715.html\" title=\"http:\/\/www.elcorreo.com\/alava\/v\/20110715\/miranda\/antigua-estacion-ferrocarril-afronta-20110715.html\" id=\"link_0\">(+)<\/a> <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Miranda El entorno de la plaza de la Estaci\u00f3n afronta la \u00faltima fase de una reforma global que arranc\u00f3 hace ya tres a\u00f1os con la terminal de autobuses; ha continuado con el redise\u00f1o de la propia plaza; y est\u00e1 centrada en estos momentos en la recuperaci\u00f3n de un lugar clave: el viejo centro de recepci\u00f3n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[2885,5963,5989,6943],"class_list":["post-2165","post","type-post","status-publish","format-standard","hentry","category-tiras-de-miranda","tag-estacion","tag-reforma","tag-rehabilitacion","tag-tren"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=2165"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/2165\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=2165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=2165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=2165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}