{"id":13232,"date":"2017-02-02T10:05:07","date_gmt":"2017-02-02T09:05:07","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/inakicerrajeria\/?p=13232"},"modified":"2017-02-02T10:05:07","modified_gmt":"2017-02-02T09:05:07","slug":"las-buenas-practicas-del-territorio","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/2017\/02\/02\/las-buenas-practicas-del-territorio\/","title":{"rendered":"Las buenas pr\u00e1cticas del territorio"},"content":{"rendered":"<p><span style=\"color: #008080;\"><strong>ARABA<\/strong><\/span><\/p>\n<p><a href=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog.jpg\"><img loading=\"lazy\" class=\"alignnone  wp-image-13233\" title=\"02-02-17blog\" src=\"\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog.jpg\" alt=\"\" width=\"614\" height=\"160\" srcset=\"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog.jpg 1031w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog-300x78.jpg 300w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog-768x200.jpg 768w, https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-content\/uploads\/sites\/29\/2017\/02\/02-02-17blog-1024x266.jpg 1024w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a><\/p>\n<p>\u00c1lava celebra hoy el d\u00eda internacional de los humedales con la frente muy alta. Dos de sus planes de conservaci\u00f3n, el de la recuperaci\u00f3n del \u00e1guila de Bonelli y la restauraci\u00f3n de las orillas y el entorno del embalse de Ull\u00edbarri-Gamboa ocupan un destacado puesto en una gu\u00eda nacional.<\/p>\n<p>Por otro lado; Urtaran sigue adelante pese al intento de EH Bildu de \u00abdesactivar\u00bb la cuesti\u00f3n de confianza.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>ARABA \u00c1lava celebra hoy el d\u00eda internacional de los humedales con la frente muy alta. Dos de sus planes de conservaci\u00f3n, el de la recuperaci\u00f3n del \u00e1guila de Bonelli y la restauraci\u00f3n de las orillas y el entorno del embalse de Ull\u00edbarri-Gamboa ocupan un destacado puesto en una gu\u00eda nacional. Por otro lado; Urtaran sigue [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[257,749,1069,3669,5230],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/13232"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/comments?post=13232"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/posts\/13232\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/media?parent=13232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/categories?post=13232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/inakicerrajeria\/wp-json\/wp\/v2\/tags?post=13232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}