{"id":51,"date":"2012-05-07T07:11:19","date_gmt":"2012-05-07T09:11:19","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/gran-cinema\/?p=51"},"modified":"2012-05-07T07:11:19","modified_gmt":"2012-05-07T09:11:19","slug":"medio-siglo-con-atticus-finch","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/gran-cinema\/2012\/05\/07\/medio-siglo-con-atticus-finch\/","title":{"rendered":"Medio siglo con Atticus Finch"},"content":{"rendered":"<p><a href=\"\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/to-kill-a-mockingbird.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-52\" title=\"to-kill-a-mockingbird\" src=\"\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/to-kill-a-mockingbird.jpg\" alt=\"\" width=\"451\" height=\"339\" srcset=\"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/to-kill-a-mockingbird.jpg 410w, https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/to-kill-a-mockingbird-300x225.jpg 300w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>El h\u00e9roe \u00edntegro de &#8216;Matar a un ruise\u00f1or&#8217; ha inspirado m\u00e1s vocaciones de abogados que cualquier otro filme<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.elcomercio.es\/v\/20120122\/sociedad\/hombre-queria-atticus-finch-20120122.html\" target=\"_blank\" rel=\"external nofollow\">Eduardo Torres-Dulce, <\/a>fiscal general del Estado, debe la vocaci\u00f3n a su padre, magistrado del Tribunal Supremo. Y a <strong>Atticus Finch<\/strong>. Cin\u00e9filo de raza, contertulio habitual de Jos\u00e9 Luis Garci, Torres-Dulce tuvo un espejo en el protagonista de &#8220;Matar a un ruise\u00f1or&#8221;. Un h\u00e9roe \u00edntegro y cotidiano que ha despertado la vocaci\u00f3n para estudiar Derecho a abogados de todo el mundo. \u00ab&#8221;Matar a un ruise\u00f1or&#8221; ofrece el fulgor evocador de un tiempo ido\u00bb, escribe el m\u00e1ximo responsable de la Fiscal\u00eda. \u00abEl final de la infancia de la narradora y quiz\u00e1s de la Rep\u00fablica Americana Liberal y confiada de los Padres Fundadores. Un retrato emocional de la vida en los secos tiempos de la Depresi\u00f3n, una mirada a c\u00f3mo fluye la vida d\u00eda tras d\u00eda, tan callando, en un tranquilo, hip\u00f3crita y violento pueblo sure\u00f1o\u00bb.<\/p>\n<p>Medio siglo despu\u00e9s de su estreno, el cl\u00e1sico de Robert Mulligan mantiene intactos sus valores cinematogr\u00e1ficos y morales. En esas encuestas a las que son tan aficionados los americanos, <strong>Atticus Finch<\/strong> suele ocupar los primeros puestos si hablamos de superh\u00e9roes nacionales. Hasta Obama admite que lo venera. Padre viudo mod\u00e9lico y ciudadano ejemplar, Atticus administra amor a sus hijos y justicia a su pueblo. Defender a un negro acusado de violar a una muchacha blanca en la Alabama de los a\u00f1os 30 exig\u00eda valor y confianza en el sistema legal. En 1962, la discriminaci\u00f3n racial en el Deep South todav\u00eda no era un tema muy habitual en el cine americano. Ni las proclamas liberales como las que suelta cada dos secuencias el protagonista: \u00abLa \u00fanica cosa que no se rige por la regla de la mayor\u00eda es la conciencia de uno\u00bb.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/ks88MPOyoYc\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<p>Aquel a\u00f1o Estados Unidos lanz\u00f3 el primer sat\u00e9lite de comunicaciones y sufri\u00f3 la &#8220;crisis de los misiles&#8221;. Sonaba el primer &#8220;single&#8221; de los Beatles y la Iglesia cat\u00f3lica celebraba el Concilio Vaticano II. El viejo &#8220;sistema de estudios&#8221; de Hollywood daba paso a una generaci\u00f3n de directores procedentes de la televisi\u00f3n. Martin Ritt, John Frankenheimer, Delbert Mann y Sidney Lumet apostaban por historias urgentes con sentido social, sin el boato de la Meca del Cine. Rodaban r\u00e1pido y barato gracias a su experiencia en los plat\u00f3s televisivos. <a href=\"http:\/\/www.imdb.es\/name\/nm0612322\/\" target=\"_blank\" rel=\"external nofollow\">Robert Mulligan<\/a> hab\u00eda luchado en la II Guerra Mundial y trabajado en &#8220;The New York Times&#8221;. Sus dos filmes m\u00e1s celebrados, &#8220;Matar a un ruise\u00f1or&#8221; y &#8221; Verano del 42&#8243;, inciden en la reconstrucci\u00f3n de un pasado a trav\u00e9s de la memoria y desde la \u00f3ptica de un ni\u00f1o.<\/p>\n<p>La figura del productor Alan J. Pakula, adalid del liberalismo en Hollywood, tambi\u00e9n resulta fundamental en una cinta que muestra un retrato poco complaciente de la Am\u00e9rica profunda y hasta po ne en solfa la sacrosanta instituci\u00f3n del jurado. Toda la verosimilitud del ficticio condado de Maycomb ya est\u00e1 contenida en la novela de Harper Lee. La autora, que gan\u00f3 el Pulitzer con su primera obra y ya nunca m\u00e1s ha vuelto a escribir, introdujo elementos autobiogr\u00e1ficos en el libro. <strong>Atticus Finch<\/strong> se inspira en su padre, un abogado que en 1919 defendi\u00f3 a dos negros acusados de asesinato. Tras su condena, ahorcamiento y mutilaci\u00f3n, nunca m\u00e1s asumi\u00f3 ning\u00fan caso relacionado con un crimen. Harper Lee tuvo a Truman Capote como compa\u00f1ero de juegos infantiles. Ella era un chicazo y \u00e9l un rarito que ceceaba y hablaba como un adulto, as\u00ed que congeniaron pronto. Su amistad dur\u00f3 toda su vida (en 1960 viajaron a Kansas juntos para investigar los asesinatos que sirvieron de base a la novela de Capote &#8220;A sangre fr\u00eda&#8221;). El ni\u00f1o repipi del filme es, claro est\u00e1, un trasunto del autor de &#8220;Desayuno en Tiffany&#8221;s&#8221;.<\/p>\n<p><a href=\"\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-53\" title=\"Annex_-_Duvall,_Robert_(To_Kill_a_Mockingbird)_01\" src=\"\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01.jpg\" alt=\"\" width=\"247\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01.jpg 2143w, https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01-247x300.jpg 247w, https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01-768x931.jpg 768w, https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-content\/uploads\/sites\/44\/2012\/05\/Annex_-_Duvall_Robert_To_Kill_a_Mockingbird_01-844x1024.jpg 844w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/a><\/p>\n<p>&#8220;Uno no comprende de veras a una persona hasta que considera las cosas desde su punto de vista, hasta que se mete en el pellejo del otro y anda por ah\u00ed como si fuera \u00e9l\u00bb. En boca de otro actor podr\u00eda sonar falso, pero Gregory Peck dota de verdad cada s\u00edlaba de sus di\u00e1logos. &#8220;Matar a un ruise\u00f1or&#8221; no se entiende sin el actor, que gan\u00f3 su \u00fanico Oscar con <strong>Atticus Finch<\/strong>, imponi\u00e9ndose aquel a\u00f1o nada menos que a Peter O&#8221;Toole, Burt Lancaster, Jack Lemmon y Marcello Mastroianni. Ni &#8220;Vacaciones en Roma&#8221;, ni &#8220;Moby Dick&#8221;, ni &#8220;El cabo del terror&#8221;. Peck siempre tuvo claro cu\u00e1l era su pel\u00edcula favorita. En su funeral, Brock Peters, el actor que encarn\u00f3 al reo negro en el filme, ley\u00f3 su paneg\u00edrico: \u00ab<strong>Atticus Finch<\/strong> le dio la oportunidad de interpretarse a s\u00ed mismo\u00bb.<\/p>\n<p>Peck acostando a sus hijos, disparando a un perro rabioso o soportando con rabia contenida el escupitajo de un vecino ha quedado como paradigma de la dignidad. \u00abNo hay que decir lo siento si no lo sientes\u00bb, alecciona a sus hijos en una f\u00e1bula con un componente m\u00e1gico que remite al mito de Frankenstein y que se respira asimismo en &#8220;El esp\u00edritu de la colmena&#8221;, de V\u00edctor Erice. Una historia de iniciaci\u00f3n que posee su h\u00e1lito fant\u00e1stico en la aparici\u00f3n de Boo Radley (Robert Duvall en su primer papel en cine), el misterioso vecino que ha vivido oculto toda su vida. \u00abMatar a un ruise\u00f1or es un grave pecado\u00bb, educa <strong>Atticus Finch<\/strong>. \u00abNo hace otra cosa que cantar para regalarnos el o\u00eddo\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Obama homenajea una de las pel\u00edculas de su vida<\/strong><\/p>\n<p>La foto de Barack Obama sentado en un autob\u00fas dio hace unos d\u00edas la vuelta al mundo. El presidente estadounidense homenajeaba a Rosa Parks, la mujer que se neg\u00f3 a ceder ese mismo asiento a un blanco en la Alabama de 1955. El veh\u00edculo se expone en el Museo Henry Ford de Dearborn, en Michigan.<br \/>\nMaestro a la hora de dotar a sus gestos de un valor simb\u00f3lico, Obama nunca ha ocultado que &#8220;Matar a un ruise\u00f1or&#8221; se encuentra entre las pel\u00edculas de su vida (&#8220;El padrino&#8221; es su favorita). <strong>Atticus Finch<\/strong> ha sido un modelo de integridad para este graduado en Derecho por Harvard, hijo de madre blanca y padre negro. Coincidiendo con los 50 a\u00f1os de su estreno, la Casa Blanca program\u00f3 un pase privado en el que el anfitri\u00f3n recibi\u00f3 a familiares de Gregory Peck y a estudiantes locales.<\/p>\n<p>Adem\u00e1s, el presidente emul\u00f3 a Jos\u00e9 Luis Garci y present\u00f3 la cinta en el canal de televisi\u00f3n por cable USA Network. Su introducci\u00f3n resume a la perfecci\u00f3n el esp\u00edritu del cl\u00e1sico de Robert Mulligan: \u00abHace 50 a\u00f1os una pel\u00edcula cautiv\u00f3 a esta naci\u00f3n. Un cuento inolvidable de coraje y convicci\u00f3n, que nos ense\u00f1\u00f3 que hay que hacer lo correcto sin importar las consecuencias y nos brind\u00f3 uno de los grandes h\u00e9roes del cine americano: <strong>Atticus Finch<\/strong>, interpretado memorablemente por Gregory Peck. Medio siglo despu\u00e9s, el valor del filme permanece. Todav\u00eda nos habla. A\u00fan nos cuenta algo sobre lo que somos como pueblo y sobre los valores que compartimos\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; El h\u00e9roe \u00edntegro de &#8216;Matar a un ruise\u00f1or&#8217; ha inspirado m\u00e1s vocaciones de abogados que cualquier otro filme &nbsp; Eduardo Torres-Dulce, fiscal general del Estado, debe la vocaci\u00f3n a su padre, magistrado del Tribunal Supremo. Y a Atticus Finch. Cin\u00e9filo de raza, contertulio habitual de Jos\u00e9 Luis Garci, Torres-Dulce tuvo un espejo en el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":59,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[42,178,187,247],"class_list":["post-51","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-atticus-finch","tag-gregory-peck","tag-harper-lee","tag-matar-a-un-ruisenor"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/posts\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/posts\/51\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/media?parent=51"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/categories?post=51"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/gran-cinema\/wp-json\/wp\/v2\/tags?post=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}