{"id":881,"date":"2010-11-29T16:37:00","date_gmt":"2010-11-29T16:37:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=881"},"modified":"2010-11-29T16:37:00","modified_gmt":"2010-11-29T16:37:00","slug":"muy-desfasados","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/11\/29\/muy-desfasados\/","title":{"rendered":"Muy desfasados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Deerhunter\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"526\" height=\"396\" \/><\/p>\n<p>Uno de los signos que definen nuestra era es la costumbre de vivir para otros: viajar para sacar fotos, emprender actividades para contarlas en el blog, existir s\u00f3lo como condici\u00f3n previa para figurar en las redes sociales. Lo de hacer cosas para la galer\u00eda tiene m\u00e1s sentido que nunca: nosotros mismos formamos parte de ese p\u00fablico que nos mira y acabamos crey\u00e9ndonos que de verdad somos eso que se ve, aunque se trate de una imagen parcial e incluso trucada que ya no se parece casi nada a nosotros. Hemos mencionado <a id=\"link_0\" title=\"http:\/\/blogs.elcorreo.com\/evadidos\/2008\/8\/27\/mentes-abiertas-orejas-cerradas\" href=\"..\/evadidos\/2008\/8\/27\/mentes-abiertas-orejas-cerradas\">alguna vez<\/a> por aqu\u00ed que esto tambi\u00e9n afecta a la m\u00fasica, ya que, con redes como last.fm, que llevan cuenta de lo que o\u00edmos y lo muestran al mundo, el componente exhibicionista que siempre ha existido en cierta parte de la afici\u00f3n se dispara. Este mes hubo un momento muy significativo: iTunes lanz\u00f3 una nueva versi\u00f3n que no era compatible con last.fm, de forma que las canciones escuchadas no aparec\u00edan en el correspondiente perfil. S\u00f3lo fueron dos o tres d\u00edas, un fin de semana, pero la gente se sublev\u00f3. \u00abNada me molesta m\u00e1s que el hecho de que mis canciones no queden registradas. Esperar hasta el lunes ser\u00e1 matador\u00bb, dec\u00eda un usuario. \u00abNecesito ver c\u00f3mo los temas se actualizan en mi perfil\u00bb, escrib\u00eda otra. La gente se lanzaba a operaciones inform\u00e1ticas para las que no estaba preparada, todo con tal de no perder ese tesoro de audiciones del fin de semana. Imaginen si no queda para la posteridad que hemos escuchado cinco canciones de Arcade Fire, cuatro de Deerhunter -en la foto de arriba- y dos de Pitingo, aunque esas a lo mejor decidimos borrarlas para que la gente no piense que nos gustan.<\/p>\n<p>\u00bfSe han dado cuenta, por cierto, de que ya proliferan <a id=\"link_1\" title=\"http:\/\/www.largeheartedboy.com\/blog\/archive\/2010\/11\/2010_yearend_on.html\" href=\"http:\/\/www.largeheartedboy.com\/blog\/archive\/2010\/11\/2010_yearend_on.html\" rel=\"external nofollow\">las listas de lo mejor de 2010<\/a>? S\u00ed, estamos todav\u00eda en noviembre y el a\u00f1o sigue teniendo un mes m\u00e1s, pero esa anticipaci\u00f3n, esa impaciencia, es otro rasgo de esta sociedad hambrienta de fen\u00f3menos, de sucesos que, por min\u00fasculos e insignificantes que sean, sirvan para alimentar la sensaci\u00f3n de vivir a la \u00faltima. He le\u00eddo por ah\u00ed el argumento de que, total, ya no quedan novedades discogr\u00e1ficas interesantes para diciembre, como si los que confeccionan esas listas hubiesen escuchado puntualmente todo lo que ha ido saliendo hasta ahora. Para el 28 de diciembre, cuando solemos hacer la <em>lista evadida<\/em>, estaremos tan desfasados como si public\u00e1semos lo mejor de 2007. Eso s\u00ed, podremos involucrarnos en otra de las grandes tendencias de nuestro tiempo: copiar.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Uno de los signos que definen nuestra era es la costumbre de vivir para otros: viajar para sacar fotos, emprender actividades para contarlas en el blog, existir s\u00f3lo como condici\u00f3n previa para figurar en las redes sociales. Lo de hacer cosas para la galer\u00eda tiene m\u00e1s sentido que nunca: nosotros mismos formamos parte de ese [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[1689,1746,2485,2852],"class_list":["post-881","post","type-post","status-publish","format-standard","hentry","category-internet","category-musica","tag-last-fm","tag-listas","tag-redes-sociales","tag-tendencias"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=881"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/881\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}