{"id":868,"date":"2010-10-26T21:21:00","date_gmt":"2010-10-26T21:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=868"},"modified":"2010-10-26T21:21:00","modified_gmt":"2010-10-26T21:21:00","slug":"navidades-silenciosas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/10\/26\/navidades-silenciosas\/","title":{"rendered":"Navidades silenciosas"},"content":{"rendered":"<p>El silencio es la nueva m\u00fasica. Qu\u00e9 frase m\u00e1s guay, \u00bfverdad?, qu\u00e9 cosa eso de escribir como un gur\u00fa dominguero. Pues no, qu\u00e9 va, el silencio no es la nueva m\u00fasica ni el nuevo ruido ni la nueva nada, pero s\u00ed que parece haberse puesto raramente de moda en las \u00faltimas semanas: tal vez hayan le\u00eddo por ah\u00ed, porque le han dado mucha cancha, que el <em>radiohead <\/em>mayor Thom Yorke y el primer ministro David Cameron van a participar en un <em>single <\/em>silencioso con ocasi\u00f3n del Remembrance Day, la jornada con la que el Reino Unido rinde homenaje a los ca\u00eddos de sus tropas. Ser\u00e1n dos minutos de silencio, pero se supone que se trata de un silencio presencial, es decir, que se pondr\u00e1n delante del micr\u00f3fono y permanecer\u00e1n calladitos. Con lo que, bueno, no deber\u00eda ser un disco realmente silencioso, porque la vida hace ruido hasta cuando quiere ser discreta, y los artilugios de los estudios modernos son capaces de registrar los rumores m\u00e1s sigilosos, esos roces y latidos y respiraciones que nos delatan.<\/p>\n<p>Con lo que llegamos a John Cage: ya saben que aqu\u00ed somos bastante amigos de traer a colaci\u00f3n <em>4\u201933\u2019\u2019<\/em>, la partitura sin notas con la que el compositor estadounidense demostraba a su manera la imposibilidad del silencio. Pues bien, tambi\u00e9n est\u00e1 de moda, porque hay <a id=\"link_0\" title=\"http:\/\/www.catm.co.uk\/index\" href=\"http:\/\/www.catm.co.uk\/index\" rel=\"external nofollow\">una campa\u00f1a<\/a> \u2013condenada al fracaso, claro\u2013 para convertirla en el n\u00famero uno de las listas navide\u00f1as del Reino Unido. All\u00ed, lo del <em>hit parade<\/em> en Navidad es una tradici\u00f3n muy cuidada que da lugar a enfrentamientos asesinos: el a\u00f1o pasado, triunf\u00f3 la campa\u00f1a que deseaba aupar el <em>Killing In The Name <\/em>de Rage Against The Machine por encima de un <em>triunfito <\/em>local, Joe McElderry, y hace un par de a\u00f1os se enfrentaron versiones distintas del <em>Hallelujah <\/em>de Leonard Cohen. Pues bien, los responsables de Cage Against The Machine, que ese el ocurrente nombre que le han puesto a la iniciativa, creen que <em>4\u201933\u2019\u2019<\/em> ser\u00eda un estupendo <em>single <\/em>navide\u00f1o. Imag\u00ednense, todos en torno a la mesa, charlando en familia, con el silencio sonando de fondo, en lugar de los grandes \u00e9xitos de Raphael y la inevitable familia Flores.<\/p>\n<p>Les dejo con una interpretaci\u00f3n orquestal de la pieza que respeta su estructura en tres movimientos. P\u00f3nganse los cascos, que hay toses, risas y roce de papel al pasar las hojas de la partitura.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/qWuNVByFVTY?rel=0\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El silencio es la nueva m\u00fasica. Qu\u00e9 frase m\u00e1s guay, \u00bfverdad?, qu\u00e9 cosa eso de escribir como un gur\u00fa dominguero. Pues no, qu\u00e9 va, el silencio no es la nueva m\u00fasica ni el nuevo ruido ni la nueva nada, pero s\u00ed que parece haberse puesto raramente de moda en las \u00faltimas semanas: tal vez hayan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[456,688,1471,2118,2673,3034],"class_list":["post-868","post","type-post","status-publish","format-standard","hentry","category-mundo-freak","category-musica","tag-campanas","tag-david-cameron","tag-john-cage","tag-navidad","tag-silencio","tag-thom-yorke"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=868"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/868\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}