{"id":864,"date":"2010-10-21T10:19:00","date_gmt":"2010-10-21T10:19:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=864"},"modified":"2021-11-06T16:42:02","modified_gmt":"2021-11-06T15:42:02","slug":"muere-ari-up","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/10\/21\/muere-ari-up\/","title":{"rendered":"Muere Ari Up"},"content":{"rendered":"<p>Ari Up, vocalista de las Slits, muri\u00f3 ayer a los 48 a\u00f1os a causa de un c\u00e1ncer. Se ha encargado de difundir la noticia la <a id=\"link_0\" title=\"http:\/\/www.johnlydon.com\/jltalk.html#Arianna\" href=\"http:\/\/www.johnlydon.com\/jltalk.html#Arianna\" rel=\"external nofollow\">p\u00e1gina web oficial<\/a> de su padrastro, John Lydon, el cantante de los Sex Pistols. Ariane Forster, que as\u00ed se llamaba en realidad, ha tenido una de esas vidas comprimidas en el tiempo, cortas en longitud pero profundas en experiencias: nieta del acaudalado propietario de <em>Der Tagesspiegel<\/em> e hija de una amiga de Jimi Hendrix que despu\u00e9s se casar\u00eda con John Lydon, Ari estaba en medio del remolino del punk brit\u00e1nico y form\u00f3 The Slits con s\u00f3lo catorce a\u00f1os. Ella fue una de las chicas que demostraron que el punk tambi\u00e9n pod\u00eda ser un sonido femenino, que incluso adquir\u00eda nuevo relieve y vitalidad en manos de las mujeres, pero su importancia no se puede reducir a esa perspectiva: las Slits tambi\u00e9n estuvieron entre los pioneros en la fusi\u00f3n de la actitud y libertad del punk con los sonidos jamaicanos, siempre con las miras abiertas a la experimentaci\u00f3n. Muchos creemos que el punk consiste m\u00e1s en eso que en las consignas baratas y los coros voceados con el pu\u00f1o en alto.<\/p>\n<p>Les dejo con su <em>Typical Girls<\/em>, lo que ella nunca fue. Ni tampoco sus compa\u00f1eras: <a id=\"link_0\" title=\"http:\/\/blogs.elcorreo.com\/evadidos\/2006\/4\/27\/paloma-palmolive-paloma\" href=\"..\/evadidos\/2006\/4\/27\/paloma-palmolive-paloma\">aqu\u00ed<\/a> y <a id=\"link_1\" title=\"http:\/\/blogs.elcorreo.com\/evadidos\/2010\/4\/9\/vuelve-viv\" href=\"..\/evadidos\/2010\/4\/9\/vuelve-viv\">aqu\u00ed<\/a> pueden leer lo que dijimos hace tiempo sobre las <em>slits <\/em>Paloma Palmolive, la espa\u00f1ola que ahora es cristiana renacida, y Viv Albertine.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"480\" height=\"385\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/ZyXGblps64M?fs=1&amp;hl=es_ES\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"480\" height=\"385\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/ZyXGblps64M?fs=1&amp;hl=es_ES\" allowfullscreen=\"allowfullscreen\" allowscriptaccess=\"always\" allowfullscreen=\"allowfullscreen\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ari Up, vocalista de las Slits, muri\u00f3 ayer a los 48 a\u00f1os a causa de un c\u00e1ncer. Se ha encargado de difundir la noticia la p\u00e1gina web oficial de su padrastro, John Lydon, el cantante de los Sex Pistols. Ariane Forster, que as\u00ed se llamaba en realidad, ha tenido una de esas vidas comprimidas en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[199,2198,2434,2988],"class_list":["post-864","post","type-post","status-publish","format-standard","hentry","category-musica","tag-ari-up","tag-obituarios","tag-punk","tag-the-slits"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=864"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/864\/revisions"}],"predecessor-version":[{"id":5326,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/864\/revisions\/5326"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}