{"id":825,"date":"2010-07-30T12:11:00","date_gmt":"2010-07-30T12:11:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=825"},"modified":"2010-07-30T12:11:00","modified_gmt":"2010-07-30T12:11:00","slug":"cancion-la-semana-cry-cry-baby","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/07\/30\/cancion-la-semana-cry-cry-baby\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Cry, Cry, Baby&#039;"},"content":{"rendered":"<p>Me gustan mucho las canciones de <a id=\"link_0\" title=\"http:\/\/www.myspace.com\/ninanastasia\" href=\"http:\/\/www.myspace.com\/ninanastasia\" rel=\"external nofollow\">Nina Nastasia<\/a>, austeras y energ\u00e9ticas como un fruto seco, pero no s\u00f3lo eso: la cantautora estadounidense de ascendencia calabresa es uno de esos artistas que me atraen en su conjunto. Me gusta su pinta, me gustan sus colaboradores -Steve Albini ha producido todos sus \u00e1lbumes- y me gusta esa actitud a la vez dura y nerviosa de quien ha de sobreponerse a todas sus inseguridades. Su anterior \u00e1lbum, una asc\u00e9tica colaboraci\u00f3n con Jim White, bater\u00eda habitual de su banda y miembro de los Dirty Three, demostraba el nivel de expresividad que se puede alcanzar s\u00f3lo con voz, guitarra y percusi\u00f3n. Ahora ha sacado <em>Outlaster<\/em>, con arreglos inusualmente lujosos dentro de su producci\u00f3n: \u00a1un cuarteto de cuerda!<\/p>\n<p>La propia Nastasia cuenta en <a id=\"link_0\" title=\"http:\/\/thequietus.com\/articles\/04455-nina-nastasia-interview-outlaster\" href=\"http:\/\/thequietus.com\/articles\/04455-nina-nastasia-interview-outlaster\" rel=\"external nofollow\">esta entrevista<\/a>, entre sorbos de whiskey Jameson, que se qued\u00f3 con la sensaci\u00f3n de que hab\u00eda hecho un disco tremendamente comercial: \u00abDespu\u00e9s de grabarlo, lo pusimos en el est\u00e9reo del coche y pens\u00e9 &#8216;oh Dios m\u00edo, hemos hecho un disco de pop&#8217;, y hab\u00eda algo excitante en ello. Parec\u00eda brillante y como si, guau, fu\u00e9semos a alcanzar el disco de platino. Entonces el disco par\u00f3, y no s\u00e9 qu\u00e9 era lo que empez\u00f3 a sonar, porque nunca escucho la radio, y nos quedamos como \u2018vaya, <em>eso <\/em>es la m\u00fasica pop\u2019. No tengo ni idea\u00bb. Vean en este bonito v\u00eddeo grabado en directo qu\u00e9 es lo que cre\u00eda pop la pobre Nina.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"480\" height=\"385\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/4BhEdUFnU80&#038;hl=es_ES&#038;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"480\" height=\"385\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/4BhEdUFnU80&#038;hl=es_ES&#038;fs=1\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me gustan mucho las canciones de Nina Nastasia, austeras y energ\u00e9ticas como un fruto seco, pero no s\u00f3lo eso: la cantautora estadounidense de ascendencia calabresa es uno de esos artistas que me atraen en su conjunto. Me gusta su pinta, me gustan sus colaboradores -Steve Albini ha producido todos sus \u00e1lbumes- y me gusta esa [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,469,2155],"class_list":["post-825","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-cantautores","tag-nina-nastasia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}