{"id":816,"date":"2010-07-09T19:25:00","date_gmt":"2010-07-09T19:25:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=816"},"modified":"2010-07-09T19:25:00","modified_gmt":"2010-07-09T19:25:00","slug":"cancion-la-semana-i-heart-california","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/07\/09\/cancion-la-semana-i-heart-california\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;I Heart California&#039;"},"content":{"rendered":"<p>Ser\u00e1 cosa de la edad, o de la sobreabundancia, pero el caso es que cada vez hay menos artistas a los que siga con verdadera fidelidad. Ll\u00e1menme descre\u00eddo, pero eso de esperar con ansiedad el nuevo disco de mis \u00eddolos me ocurre en pocas ocasiones. Ya les digo: quiz\u00e1 esa fiebre sea m\u00e1s propia de la primera juventud, cuando me desviv\u00eda por comprarme los lanzamientos de Sonic Youth o los Pixies, o quiz\u00e1 simplemente sea m\u00e1s propia de otra \u00e9poca hist\u00f3rica, de aquel tiempo en el que la m\u00fasica que se escuchaba estaba fatalmente limitada por el presupuesto, con la consiguiente especializaci\u00f3n. Como ya he comentado por aqu\u00ed demasiadas veces, porque todo fan es pelmazo por definici\u00f3n, uno de los \u00faltimos nombres de los que me sent\u00ed realmente devoto fue Grandaddy, la banda californiana que <a id=\"link_1\" title=\"http:\/\/blogs.elcorreo.com\/evadidos\/2006\/1\/30\/abuelito-adios\" href=\"..\/evadidos\/2006\/1\/30\/abuelito-adios\">se separ\u00f3 en 2006<\/a>. Y desde entonces sigo con lealtad perruna a su l\u00edder, Jason Lytle, que sac\u00f3 un \u00e1lbum en solitario y ahora ha formado un nuevo grupo, <a id=\"link_0\" title=\"http:\/\/www.admiralradley.com\/homenews\/\" href=\"http:\/\/www.admiralradley.com\/homenews\/\" rel=\"external nofollow\">Admiral Radley<\/a>. Ya les cont\u00e9 hace unas semanas que pod\u00edan descargarse gratuitamente su primer sencillo, <em>I Heart California<\/em>, pero he visto que han hecho un v\u00eddeo (una cosita tipo karaoke) y no quiero desperdiciar la ocasi\u00f3n de colgarlo por aqu\u00ed. Suena bastante a Grandaddy, qu\u00e9 bien.<\/p>\n<div class=\"topspin-widget topspin-widget-bundle-widget\"><object id=\"TSWidget28681\" style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"400\" height=\"400\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"quality\" value=\"high\" \/><param name=\"flashvars\" value=\"highlightColor=0x6699cc&#038;theme=white&#038;widget_id=http:\/\/app.topspin.net\/api\/v1\/artist\/1579\/bundle_widget\/28681&#038;theme=white\" \/><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/cdn.topspin.net\/widgets\/bundle\/swf\/TSBundleWidget.swf?timestamp=1278684509\" \/><embed id=\"TSWidget28681\" style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"400\" height=\"400\" type=\"application\/x-shockwave-flash\" src=\"\/\/cdn.topspin.net\/widgets\/bundle\/swf\/TSBundleWidget.swf?timestamp=1278684509\" allowScriptAccess=\"always\" allowfullscreen=\"true\" quality=\"high\" flashvars=\"highlightColor=0x6699cc&#038;theme=white&#038;widget_id=http:\/\/app.topspin.net\/api\/v1\/artist\/1579\/bundle_widget\/28681&#038;theme=white\" wmode=\"transparent\" \/><\/object><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 cosa de la edad, o de la sobreabundancia, pero el caso es que cada vez hay menos artistas a los que siga con verdadera fidelidad. Ll\u00e1menme descre\u00eddo, pero eso de esperar con ansiedad el nuevo disco de mis \u00eddolos me ocurre en pocas ocasiones. Ya les digo: quiz\u00e1 esa fiebre sea m\u00e1s propia de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[60,461,1188,1418],"class_list":["post-816","post","type-post","status-publish","format-standard","hentry","category-musica","tag-admiral-radley","tag-cancion-de-la-semana","tag-grandaddy","tag-jason-lytle"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}