{"id":797,"date":"2010-05-08T09:00:00","date_gmt":"2010-05-08T09:00:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=797"},"modified":"2010-05-08T09:00:00","modified_gmt":"2010-05-08T09:00:00","slug":"cancion-la-semana-torturing-james-hetfield","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/05\/08\/cancion-la-semana-torturing-james-hetfield\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Torturing James Hetfield&#039;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Chumbawamba\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"553\" height=\"116\" \/><a id=\"link_1\" title=\"http:\/\/www.chumba.com\/\" href=\"http:\/\/www.chumba.com\/\" rel=\"external nofollow\">Chumbawamba<\/a>, a los que tienen aqu\u00ed encima en una foto de Casey Orr, son un veteran\u00edsimo grupo brit\u00e1nico del que se suelen saber tres cosas: que son anarquistas, que tuvieron <a id=\"link_0\" title=\"http:\/\/www.youtube.com\/watch?v=GAM9diIDHqs&#038;feature=fvst\" href=\"http:\/\/www.youtube.com\/watch?v=GAM9diIDHqs&#038;feature=fvst\" rel=\"external nofollow\">una canci\u00f3n de \u00e9xito<\/a> de la que seguramente siguen viviendo y que batieron el r\u00e9cord mundial de t\u00edtulo m\u00e1s largo con su \u00e1lbum&#8230; estooo&#8230; \u00bfme permiten un punto y aparte?<\/p>\n<p><em>The Boy Bands Have Won, and All the Copyists and the Tribute Bands and the TV Talent Show Producers Have Won, If We Allow Our Culture to Be Shaped by Mimicry, Whether from Lack of Ideas or From Exaggerated Respect. You Should Never Try to Freeze Culture. What You Can Do Is Recycle That Culture. Take Your Older Brother&#8217;s Hand-Me-Down Jacket and Re-Style It, Re-Fashion It to the Point Where It Becomes Your Own. But Don&#8217;t Just Regurgitate Creative History, or Hold Art and Music and Literature as Fixed, Untouchable and Kept Under Glass. The People Who Try to &#8216;Guard&#8217; Any Particular Form of Music Are, Like the Copyists and Manufactured Bands, Doing It the Worst Disservice, Because the Only Thing That You Can Do to Music That Will Damage It Is Not Change It, Not Make It Your Own. Because Then It Dies, Then It&#8217;s Over, Then It&#8217;s Done, and the Boy Bands Have Won.<\/em><\/p>\n<p>Eso es el t\u00edtulo, s\u00ed. Por supuesto, no hay que sab\u00e9rselo, basta con cortapegarlo de la Wikipedia. En fin, Chumbawamba tienen una biograf\u00eda bastante amena: en una ocasi\u00f3n, animaron a la gente a robar sus discos; en otra, uno de sus miembros se desnud\u00f3 y se puso a bailar delante de los Smashing Pumpkins. Y el tema suyo que traemos hoy, como habr\u00e1n observado, se titula <em>Torturando a James Hetfield<\/em>. En el primer minuto y medio del v\u00eddeo, que es de presentaci\u00f3n, se recuerda que el vocalista de Metallica apoy\u00f3 el uso de su m\u00fasica como medio de tortura por parte de las tropas estadounidenses. As\u00ed que, en la letra de esta canci\u00f3n, le dan a probar un poco de su propia medicina: tras atarlo bien fuerte, le hacen escuchar a Simply Red <em>non stop<\/em> y, como cruel soluci\u00f3n final, le ponen los <em>grandes \u00e9xitos<\/em> de Chumbawamba (&#8220;s\u00f3lo hay uno&#8221;, puntualiza la letra). M\u00e1s all\u00e1 de la gracia, ese estribillo de &#8220;James, James, James, just give us names, names, names&#8221; me tiene enganchad\u00edsimo desde la primera vez que lo escuch\u00e9. Por cierto, aunque aqu\u00ed lo tapen las risas, al final James les da esos nombres que le piden: fue Lars, dice el muy chivato.<\/p>\n<p><object style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/jP76X-9JwVM&#038;hl=es_ES&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/jP76X-9JwVM&#038;hl=es_ES&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Chumbawamba, a los que tienen aqu\u00ed encima en una foto de Casey Orr, son un veteran\u00edsimo grupo brit\u00e1nico del que se suelen saber tres cosas: que son anarquistas, que tuvieron una canci\u00f3n de \u00e9xito de la que seguramente siguen viviendo y que batieron el r\u00e9cord mundial de t\u00edtulo m\u00e1s largo con su \u00e1lbum&#8230; estooo&#8230; \u00bfme [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,556,1406,1960],"class_list":["post-797","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-chumbawamba","tag-james-hetfield","tag-metallica"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=797"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/797\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}