{"id":790,"date":"2010-04-18T19:41:00","date_gmt":"2010-04-18T19:41:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=790"},"modified":"2010-04-18T19:41:00","modified_gmt":"2010-04-18T19:41:00","slug":"cementerio-discos-perdidos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/04\/18\/cementerio-discos-perdidos\/","title":{"rendered":"Cementerio de discos perdidos"},"content":{"rendered":"<p>La revista <em>Uncut <\/em>publica este mes un reportaje muy curioso sobre cincuenta &#8220;\u00e1lbumes perdidos&#8221;, es decir, discos que en este momento no est\u00e1n disponibles para descargarlos legalmente o para comprarlos en un ced\u00e9 nuevo. Por supuesto, la trascendencia de esta desaparici\u00f3n es mucho menor que en otros tiempos, porque todos ellos se encontrar\u00e1n con facilidad en alg\u00fan rinc\u00f3n m\u00e1s o menos oscuro de la red, pero me ha llamado la atenci\u00f3n que la lista incluya a artistas tan conocidos como los Who, David Bowie, Tom Waits o los Beatles. En el n\u00famero uno, los cr\u00edticos de la revista sit\u00faan <em>Time Fades Away<\/em>, un directo que edit\u00f3 Neil Young en 1973 y que jam\u00e1s ha llegado a salir en ced\u00e9, al parecer porque el propio Young lo considera su peor disco (y eso es mucho decir en una carrera tan larga y tan zigzagueante como la de este hombre). El \u00e1lbum es el reflejo de una gira en la que Young estaba an\u00edmicamente hundido: el 18 de noviembre de 1972 ech\u00f3 de la banda al guitarrista Charlie Whitten, enganchado a la hero\u00edna, y esa misma noche el m\u00fasico muri\u00f3 por una mezcla de valium y alcohol. Young, que acababa de alcanzar el \u00e9xito masivo con <em>Harvest<\/em>, prefiri\u00f3 consagrar sus conciertos a canciones nuevas interpretadas con un sonido crudo por una banda al borde del colapso. Por pura casualidad, yo tengo el vinilo (conste que poseo poqu\u00edsimos discos de Neil Young, pero \u00e9ste lo compr\u00e9 de segunda mano por cien pesetas, bastante desastrado) y no est\u00e1 tan mal como Neil Young parece creer, sobre todo una vez que se sabe en qu\u00e9 condiciones mentales est\u00e1 grabado. Por si les pica la curiosidad, les copio los diez primeros discos de la lista:<\/p>\n<p><strong> 1. Neil Young<\/strong> &#8211; Time Fades Away (1973)<br \/>\n<strong>2. Captain Beefheart &#038; The Magic Band<\/strong> &#8211; Lick My Decals Off, Baby (1970)<br \/>\n<strong>3. Van Morrison<\/strong> &#8211; St Dominic&#8217;s Preview (1972)<br \/>\n<strong>4. The Beatles<\/strong> &#8211; The Beatles At The Hollywood Bowl (1977)<br \/>\n<strong>5. Jonathan Richman &#038; The Modern Lovers<\/strong> &#8211; It&#8217;s Time For&#8230; (1986)<br \/>\n<strong>6. Tom Waits<\/strong> &#8211; Night On Earth OST (1992)<br \/>\n<strong>7. Kraftwerk<\/strong> &#8211; Kraftwerk (1970)<br \/>\n<strong>8. Sandy Denny &#038; The Strawbs<\/strong> &#8211; All Our Own Work (1973)<br \/>\n<strong>9. Big Black<\/strong> &#8211; Atomizer (1986)<br \/>\n<strong>10. John Cale<\/strong> &#8211; Music For A New Society (1982)<\/p>\n<p>Y, dado que el n\u00famero nueve es uno de mis discos preferidos de todos los tiempos, les cuelgo el tema que lo abre, <em>Jordan, Minnesota<\/em>, y as\u00ed de paso hago un homenaje pendiente a Iain Burgess, productor de este \u00e1lbum y de otro buen mont\u00f3n de salvajadas, que falleci\u00f3 hace unos meses. La canci\u00f3n se basa en las denuncias por abusos sexuales y rituales sat\u00e1nicos que condujeron al arresto de 24 vecinos de esa localidad de Minnesota en 1983, aunque cuenta la Wikipedia que todos fueron finalmente exonerados. &#8220;Esto es Jordan, hacemos lo que nos gusta&#8221;, canta Steve Albini, siempre buscando temas agradables para sus luminosas canciones.<\/p>\n<p><object style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/FK7CbLlrqek&#038;hl=es_ES&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/FK7CbLlrqek&#038;hl=es_ES&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La revista Uncut publica este mes un reportaje muy curioso sobre cincuenta &#8220;\u00e1lbumes perdidos&#8221;, es decir, discos que en este momento no est\u00e1n disponibles para descargarlos legalmente o para comprarlos en un ced\u00e9 nuevo. Por supuesto, la trascendencia de esta desaparici\u00f3n es mucho menor que en otros tiempos, porque todos ellos se encontrar\u00e1n con facilidad [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[321,774,1702,1746,2125],"class_list":["post-790","post","type-post","status-publish","format-standard","hentry","category-musica","tag-big-black","tag-discos","tag-lecturas","tag-listas","tag-neil-young"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=790"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/790\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}