{"id":780,"date":"2010-05-17T11:16:00","date_gmt":"2010-05-17T11:16:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=780"},"modified":"2010-05-17T11:16:00","modified_gmt":"2010-05-17T11:16:00","slug":"img-src-blogfile","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/05\/17\/img-src-blogfile\/","title":{"rendered":"La noche ilegal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Ilegales, con Jorge Mart\u00ednez a la derecha de la foto\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/Ilegales90.JPG\" alt=\"\" width=\"520\" height=\"383\" \/><\/p>\n<p>Qu\u00e9 gusto da ver a Ilegales en directo, un placer del que -si esta gira es realmente de despedida, como anuncian- nos veremos privados durante unos a\u00f1itos o quiz\u00e1 para siempre, que es demasiado tiempo. El s\u00e1bado, en el Antzoki, Jorge Mart\u00ednez nos proporcion\u00f3 dos horas y pico de <a id=\"link_0\" title=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/gps\/musica\/140510\/bafle-ilegales.html\" href=\"http:\/\/www.elcorreo.com\/vizcaya\/ocio\/gps\/musica\/140510\/bafle-ilegales.html\" rel=\"external nofollow\">m\u00fasica impecable<\/a> que nos dej\u00f3 con una sonrisa tonta y la duda de siempre en la cabeza: si este hombre consigue que la guitarra suene as\u00ed de bien, alternando entre la r\u00edtmica y los solos con la facilidad de quien se rasca la calva, \u00bfqu\u00e9 diablos falla en tantos guitarristas de rock para que lo suyo parezca m\u00e1s bien un engrudo sonoro o, como mucho, un aprobadillo logrado con mucho esfuerzo?<\/p>\n<p>En fin, que Ilegales son enormes, una afortunada conjunci\u00f3n de letras, melod\u00eda, sonido y actitud que no se da todos los d\u00edas; en realidad, no se da casi nunca. Todo lo que digamos que son lo son y a\u00fan mejor. En m\u00e1s de dos horas caben muchas canciones de Ilegales, pero mis hitos fueron ese adictivo doblete de <em>El norte est\u00e1 lleno de fr\u00edo<\/em> y <em>Enamorados de Varsovia<\/em>, como siempre, y tambi\u00e9n <em>Regreso al sexo qu\u00edmicamente puro<\/em>, porque uno tiene debilidad por las canciones de modelos de Jorge Mart\u00ednez (ni les cuento si hubiesen tocado <em>Me gusta c\u00f3mo huele<\/em>s). Ahora empieza la era de Jorge Ilegal y los Magn\u00edficos, pero todos pensamos que m\u00e1s tarde o m\u00e1s temprano Ilegales volver\u00e1n, \u00bfno?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 gusto da ver a Ilegales en directo, un placer del que -si esta gira es realmente de despedida, como anuncian- nos veremos privados durante unos a\u00f1itos o quiz\u00e1 para siempre, que es demasiado tiempo. El s\u00e1bado, en el Antzoki, Jorge Mart\u00ednez nos proporcion\u00f3 dos horas y pico de m\u00fasica impecable que nos dej\u00f3 con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[602,1332,1501],"class_list":["post-780","post","type-post","status-publish","format-standard","hentry","category-musica","tag-conciertos","tag-ilegales","tag-jorge-martinez"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}