{"id":78,"date":"2005-12-22T20:59:07","date_gmt":"2005-12-22T20:59:07","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=78"},"modified":"2005-12-22T20:59:07","modified_gmt":"2005-12-22T20:59:07","slug":"el-canto-los-mileuristas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2005\/12\/22\/el-canto-los-mileuristas\/","title":{"rendered":"El canto de los mileuristas"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/evadidos\/files\/PublicodeBattiato.jpg\" alt=\"\" \/><\/p>\n<p>Varios centenares de <a href=\"http:\/\/www.nodo50.org\/torrent\/spip\/article.php3?id_article=84\" target=\"_blank\" rel=\"external nofollow\">mileuristas<\/a> se dieron cita el lunes en el Teatro Real de Madrid para asistir al \u00fanico concierto en Espa\u00f1a de <a href=\"http:\/\/www.battiato.it\/\" target=\"_blank\" rel=\"external nofollow\">Franco Battiato<\/a>. El cantante italiano actu\u00f3 acompa\u00f1ado por una joven orquesta compuesta por cuarenta m\u00fasicos y sus colaboradores habituales: el teclista Angelo Privitera, el pianista Carlo Guaitoli y el fil\u00f3sofo de c\u00e1mara del artista, el sin par Manlio Sgalambro, que a sus ochenta a\u00f1os interpret\u00f3 la introducci\u00f3n (&#8216;Teor\u00eda sobre Sicilia&#8217;) y otras dos canciones durante el descanso. Durante alg\u00fan tiempo, albergu\u00e9 la sospecha de que Battiato y Sgalambro eran la misma persona. Un cantante filos\u00f3fico y un fil\u00f3sofo cantante es m\u00e1s de lo que se puede permitir un pa\u00eds como Italia, pero el lunes coincidieron sobre el escenario y disiparon mis dudas. El caso es que Sgalambro enton\u00f3 &#8216;La mer&#8217; y &#8216;La vie en rose&#8217; con el br\u00edo de un cantante mel\u00f3dico de los a\u00f1os cincuenta, y lo que probablemente empez\u00f3 como una broma por parte de Battiato, ha terminado por convertirse en uno de los momentos m\u00e1s esperados de sus recitales, como los cl\u00e1sicos de los a\u00f1os ochenta, que prodiga poco pese a la furiosa reacci\u00f3n del p\u00fablico, que nunca los agradece bastante. El lunes, Battiato nos regal\u00f3 &#8216;N\u00f3madas&#8217;, &#8216;Y te vengo a buscar&#8217; y &#8216;Horizontes perdidos&#8217;, canciones que lo convirtieron hace veinte a\u00f1os en un fen\u00f3meno de ventas en Espa\u00f1a e Italia. Los mileuristas presentes en el recital, incluidos los que aforaron sesenta eurazos por una localidad de butaca, forman una extra\u00f1a generaci\u00f3n de fans que se alfabetizaron musicalmente con los discos de Battiato que en los a\u00f1os ochenta compraron sus padres sin considerar enteramente las consecuencias.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Varios centenares de mileuristas se dieron cita el lunes en el Teatro Real de Madrid para asistir al \u00fanico concierto en Espa\u00f1a de Franco Battiato. El cantante italiano actu\u00f3 acompa\u00f1ado por una joven orquesta compuesta por cuarenta m\u00fasicos y sus colaboradores habituales: el teclista Angelo Privitera, el pianista Carlo Guaitoli y el fil\u00f3sofo de c\u00e1mara [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[602,1071,1847,1875],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","category-musica","tag-conciertos","tag-franco-battiato","tag-madrid","tag-manlio-sgalambro"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}