{"id":751,"date":"2010-01-15T09:22:00","date_gmt":"2010-01-15T09:22:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=751"},"modified":"2010-01-15T09:22:00","modified_gmt":"2010-01-15T09:22:00","slug":"cancion-la-semana-la-hora-volve","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2010\/01\/15\/cancion-la-semana-la-hora-volve\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;La hora de volv\u00e9&#039;"},"content":{"rendered":"<p>Pido perd\u00f3n por hablar desde el desconocimiento, pero creo que el merengue es la m\u00fasica que menos me gusta. Supongo que est\u00e1 concebida para bailar, una actividad con la que siempre he sido incompatible. Y, sin embargo, dicen que nuestra canci\u00f3n de esta semana, <em>La hora de volv\u00e9<\/em>, es un merengue de vanguardia, aunque me imagino que los puristas de lo sabros\u00f3n se rasgar\u00e1n las vestiduras al verse relacionados con estos sonidos y estas gentes.<\/p>\n<p>En fin, Rita Indiana es una cantante de la Rep\u00fablica Dominicana -justo al lado de ese Hait\u00ed que estos d\u00edas anda hundido en la desolaci\u00f3n y el dolor- y tambi\u00e9n ha editado novelas y poes\u00eda. F\u00edsicamente resulta bastante imponente: alt\u00edsima, delgad\u00edsima, con un cabello muy corto que le da una apariencia andr\u00f3gina y turbadora. Y musicalmente tampoco es lo m\u00e1s convencional del mundo. En estos tiempos de reciclajes vendidos como propuestas novedosas, a m\u00ed esta canci\u00f3n de Rita Indiana y Los Misterios me suena tan original que incluso me deja un poco perplejo, y eso sin afrontar siquiera la empresa de entender toda la letra. Que s\u00ed, que es en espa\u00f1ol, pero&#8230;<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: continuous;\" width=\"560\" height=\"340\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/QWd8K-YniNk&#038;hl=es_ES&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: continuous;\" width=\"560\" height=\"340\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/QWd8K-YniNk&#038;hl=es_ES&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pido perd\u00f3n por hablar desde el desconocimiento, pero creo que el merengue es la m\u00fasica que menos me gusta. Supongo que est\u00e1 concebida para bailar, una actividad con la que siempre he sido incompatible. Y, sin embargo, dicen que nuestra canci\u00f3n de esta semana, La hora de volv\u00e9, es un merengue de vanguardia, aunque me [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,2500,2518],"class_list":["post-751","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-republica-dominicana","tag-rita-indiana"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/751\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}