{"id":74,"date":"2005-12-18T16:34:00","date_gmt":"2005-12-18T16:34:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=74"},"modified":"2005-12-18T16:34:00","modified_gmt":"2005-12-18T16:34:00","slug":"horatio-jubilate","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2005\/12\/18\/horatio-jubilate\/","title":{"rendered":"Horatio, jub\u00edlate"},"content":{"rendered":"<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Horatio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-1427\" title=\"David Caruso como Horatio Caine\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Horatio.jpg\" alt=\"\" width=\"157\" height=\"280\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Horatio.jpg 250w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Horatio-84x150.jpg 84w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Horatio-169x300.jpg 169w\" sizes=\"auto, (max-width: 157px) 100vw, 157px\" \/><\/a>Ya est\u00e1 en los videoclubes, al menos en el m\u00edo, el <a href=\"http:\/\/www.csifiles.com\/news\/200505_03.shtml\" target=\"_blank\" rel=\"external nofollow\">doble cap\u00edtulo<\/a> de &#8216;C.S.I. Las Vegas&#8217; dirigido por Quentin Tarantino. Antes de nada, se lo recomiendo: yo ten\u00eda un poco de miedo de que el toque <em>tarantinesco<\/em> desvirtuase unos personajes perfectamente definidos, pero, aunque es cierto que a veces les hace parlotear m\u00e1s que de costumbre, la verdad es que ha sabido respetar la esencia de la serie. Y todo ello, con un enterrado en vida como centro del argumento, que es una cosa que siempre entretiene. El DVD ha supuesto un bonito reencuentro con &#8216;C.S.I. Las Vegas&#8217; y ha hecho rebrotar en m\u00ed la aversi\u00f3n hacia &#8216;C.S.I. Miami&#8217;, que cada semana se manifiesta con mayor virulencia. Creo que el personaje televisivo que m\u00e1s odio -bueno, despu\u00e9s del detestable <a href=\"http:\/\/www.controlpublicidad.com\/creatividad\/television\/object.php?o=11376\" target=\"_blank\" rel=\"external nofollow\">Rizo<\/a>, el erizo listillo de los seguros- es Horatio Caine, ese teniente deslavado con cara de tortuga al que da vida -expres\u00e9moslo as\u00ed- David Caruso. El pesado de Hache siempre dice la \u00faltima palabra en todo di\u00e1logo, y esa \u00faltima palabra es invariablemente una estupidez con pretensiones de trascendencia. Los guionistas nos lo quieren presentar como un tipo duro con un rigor \u00e9tico admirable, pero queda como un simple soseras que va de guay. Y lo peor llega cuando intentan que exprese sentimientos complejos, como afecto o compasi\u00f3n -su gestualidad se limita a achinar los ojos y estirar las comisuras de los labios-, o cuando le ponen a hablar con alg\u00fan ni\u00f1o, en plan poli majo que se interesa por el b\u00e9isbol alev\u00edn: \u00a1hasta Isabel Gemio lo hac\u00eda mejor! Ya, ya s\u00e9 que mezclo personaje y actor, pero es que no s\u00e9 cu\u00e1l de los dos me da m\u00e1s rabia.<\/p>\n<p>Como ya me he desahogado, no me referir\u00e9 a la marisabidilla de bal\u00edstica ni a la forense pasmada que habla a los muertos. Seguro que, si le encargan a Tarantino un &#8216;C.S.I. Miami&#8217;, los entierra vivos a todos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 en los videoclubes, al menos en el m\u00edo, el doble cap\u00edtulo de &#8216;C.S.I. Las Vegas&#8217; dirigido por Quentin Tarantino. Antes de nada, se lo recomiendo: yo ten\u00eda un poco de miedo de que el toque tarantinesco desvirtuase unos personajes perfectamente definidos, pero, aunque es cierto que a veces les hace parlotear m\u00e1s que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[649,689,1300,3294,2848],"class_list":["post-74","post","type-post","status-publish","format-standard","hentry","category-inclasificables","tag-csi","tag-david-caruso","tag-horatio-caine","tag-quentin-tarantino","tag-television"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}