{"id":723,"date":"2009-11-17T12:12:00","date_gmt":"2009-11-17T12:12:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=723"},"modified":"2009-11-17T12:12:00","modified_gmt":"2009-11-17T12:12:00","slug":"rammstein-llamas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/11\/17\/rammstein-llamas\/","title":{"rendered":"Rammstein en llamas"},"content":{"rendered":"<p>Me lo pas\u00e9 pipa el s\u00e1bado con el cabar\u00e9 apocal\u00edptico de Rammstein en el BEC. La m\u00fasica estuvo bien \u2013sin ser exactamente fan de los alemanes, es cierto que su estilo viene a ser una ramificaci\u00f3n de cosas que me gustan mucho, desde Laibach hasta Ministry, y me parece evidente que los tipos han sabido dar en el clavo mel\u00f3dico con bastantes de sus canciones, como <em>Engel<\/em>, <em>Sonne <\/em>o <em>Seemann<\/em>\u2013, pero su peso en el conjunto del espect\u00e1culo resulta mucho menos determinante que en otros conciertos. Porque Rammstein son unos maestros del show siderometal\u00fargico: hubo derroche de pirotecnia e incluso de piroman\u00eda, con especial menci\u00f3n para los cohetes que sobrevolaron en horizontal a los espectadores en un momento de <em>Du Hast<\/em> y para la m\u00e1gica cascada de chispas derramada desde una inofensiva lechera. El teclista naveg\u00f3 sobre el p\u00fablico en su barca hinchable, el vocalista se ajust\u00f3 su polla-ca\u00f1\u00f3n y ba\u00f1\u00f3 en espuma a las primeras filas, incluso prendieron fuego a un tipo con un lanzallamas. Y la iluminaci\u00f3n fue seguramente la m\u00e1s fascinante que he visto jam\u00e1s en un concierto.<\/p>\n<p>Eso s\u00ed, por muy atractivo visualmente que fuese el asunto, no entiendo qu\u00e9 pintaba mi vecino de concierto grabando todo el rato con su tel\u00e9fono m\u00f3vil. Bueno, todo el rato no, porque las canciones m\u00e1s tranquilas no le gustaban y se permiti\u00f3 bajar el brazo en un par de ocasiones, que aprovech\u00f3 para empolvarse la nariz junto a un amigo. Y, como \u00e9l, decenas de personas enarbolaban sus maquinitas para registrar no ya momentos clave, sino la pr\u00e1ctica totalidad de la actuaci\u00f3n, supongo que con sonido infecto e imagen indiscernible (en el caso de mi vecino, lo de la imagen lo s\u00e9 de buena tinta, porque pude ver todo el rato su pantallita), y pasaban m\u00e1s tiempo mirando sus diminutos aparatos que el gran circo del escenario. Imagino que muchas de esas grabaciones estar\u00e1n en YouTube y podr\u00eda colgarles una, pero optar\u00e9 por un videoclip: si prefieren, en vez de verlo directamente, pueden grabarlo con su tel\u00e9fono para luego estar seguros de que lo han visto.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/1j2m0BbLpWc&#038;hl=es_ES&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/1j2m0BbLpWc&#038;hl=es_ES&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me lo pas\u00e9 pipa el s\u00e1bado con el cabar\u00e9 apocal\u00edptico de Rammstein en el BEC. La m\u00fasica estuvo bien \u2013sin ser exactamente fan de los alemanes, es cierto que su estilo viene a ser una ramificaci\u00f3n de cosas que me gustan mucho, desde Laibach hasta Ministry, y me parece evidente que los tipos han sabido [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[270,327,602,2460],"class_list":["post-723","post","type-post","status-publish","format-standard","hentry","category-musica","tag-barakaldo","tag-bilbao","tag-conciertos","tag-rammstein"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=723"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/723\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}