{"id":720,"date":"2009-11-07T18:50:00","date_gmt":"2009-11-07T18:50:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=720"},"modified":"2009-11-07T18:50:00","modified_gmt":"2009-11-07T18:50:00","slug":"cancion-la-semana-mentia","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/11\/07\/cancion-la-semana-mentia\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Ment\u00eda&#039;"},"content":{"rendered":"<p>Si no les gusta o incluso les indigna la canci\u00f3n de esta semana, \u00e9chenle la culpa a Nacho Canut, que es el responsable de que haya prestado atenci\u00f3n al grupo argentino Miranda!. Yo ten\u00eda ese nombre archivado en el privad\u00edsimo y repleto caj\u00f3n mental llamado &#8216;artistas a los que jam\u00e1s he escuchado pero que creo que no me gustan&#8217;, junto con otros mucho m\u00e1s relevantes y por lo tanto a\u00fan menos confesables, pero Canut escribi\u00f3 el mes pasado en <a id=\"link_0\" title=\"http:\/\/www.spicnic.com\/opinion\/\" href=\"http:\/\/www.spicnic.com\/opinion\/\" rel=\"external nofollow\">su blog<\/a> que el anterior \u00e1lbum de Miranda! es uno de sus discos favoritos de todos los tiempos, as\u00ed que decid\u00ed darles una oportunidad, porque Canut suele recomendar cosas buenas como la ventresca de Auchan o los raviolis Rana de pera y queso.<\/p>\n<p>En fin, que aqu\u00ed tienen la resplandeciente <em>Ment\u00eda<\/em>, un estribillo ultracomercial que puede agujerearles el cerebro y tenerles canturreando todo el d\u00eda. Lo digo por experiencia, claro. Como contexto, si saben tan poco de Miranda! como sab\u00eda yo, quiz\u00e1 les baste saber que definen lo suyo como &#8220;electropop melodram\u00e1tico&#8221; y que han compartido alguna gira con Fangoria -aj\u00e1- y alg\u00fan concierto con&#8230; Pimpinela, los grandes maestros del melodrama musicado.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: continuous;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/BMW7btkimMY&#038;hl=es&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: continuous;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/BMW7btkimMY&#038;hl=es&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si no les gusta o incluso les indigna la canci\u00f3n de esta semana, \u00e9chenle la culpa a Nacho Canut, que es el responsable de que haya prestado atenci\u00f3n al grupo argentino Miranda!. Yo ten\u00eda ese nombre archivado en el privad\u00edsimo y repleto caj\u00f3n mental llamado &#8216;artistas a los que jam\u00e1s he escuchado pero que creo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[198,461,2005,2381],"class_list":["post-720","post","type-post","status-publish","format-standard","hentry","category-musica","tag-argentina","tag-cancion-de-la-semana","tag-miranda","tag-pop"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/720\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}