{"id":71,"date":"2005-12-14T16:54:00","date_gmt":"2005-12-14T16:54:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=71"},"modified":"2005-12-14T16:54:00","modified_gmt":"2005-12-14T16:54:00","slug":"chicos-palidos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2005\/12\/14\/chicos-palidos\/","title":{"rendered":"Chicos p\u00e1lidos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Thomas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1431\" title=\"David Thomas\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Thomas.jpg\" alt=\"\" width=\"536\" height=\"357\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Thomas.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Thomas-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2005\/12\/Thomas-300x200.jpg 300w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Este s\u00e1bado, a los <em>evadidos<\/em> nos toca dividirnos. El compa\u00f1ero Galante anunci\u00f3 con tiempo su prop\u00f3sito de acudir a Santana 27 para el concierto de<a href=\"http:\/\/blogs.elcorreo.com\/index.php\/evadidos\/2005\/11\/07\/\" target=\"_blank\">Turbonegro<\/a>, \u00ablos Village People del punk noruego\u00bb. A m\u00ed, aunque estoy convencido de que lo pasar\u00e9 peor, me llama m\u00e1s bajar a Bilborock para ver a <a href=\"http:\/\/www.ubuprojex.net\/pbs.html\" target=\"_blank\" rel=\"external nofollow\">David Thomas &#038; Two Pale Boys<\/a> dentro del festival <a href=\"http:\/\/www.musicaexmachina.com\/mem05\/programa.shtml\" target=\"_blank\" rel=\"external nofollow\">Musica Ex Machina<\/a>. David Thomas es el se\u00f1or raro de la foto, el de las barbas y el sombrero, y figura en toda historia del rock que se precie como vocalista de Pere Ubu, quiz\u00e1 el grupo que mejor supo encarrilar la furia punk por los senderos de la vanguardia. Si quieren una muestra de su arte, busquen por ah\u00ed su canci\u00f3n &#8216;Non-alignment pact&#8217;: los primeros temas de los primeros \u00e1lbumes siempre resultan reveladores. Con el tiempo, la vanguardia ha ganado el pulso al punk -el concierto de Pere Ubu en Calahorra hace unos a\u00f1os parec\u00eda folk extraterrestre- y se ha impuesto hasta definir a la perfecci\u00f3n lo que hace Thomas con Two Pale Boys. Los <em>chicos p\u00e1lidos <\/em>en cuesti\u00f3n tocan la trompeta y la guitarra, aunque pocas veces suenen como una trompeta o una guitarra convencionales, y se han hecho un poco m\u00e1s famosos desde que acompa\u00f1aron a Frank Black en su disco de revisiones de los Pixies.<\/p>\n<p>De David Thomas &#038; Two Pale Boys dice mucho el hecho de que hayan redactado un manifiesto con su \u00abdoctrina\u00bb, una especie de po\u00e9tica en tercera persona que reza as\u00ed: \u00abUna canci\u00f3n es mejor las dos o tres primeras veces que se toca. Los m\u00fasicos est\u00e1n excitados y ansiosos y no hay nada que recordar o hacer bien. Nada puede fallar. El objeto de David Thomas y Two Pale Boys es lograr esa claridad sin recurrir al tipo de improvisaci\u00f3n incoherente que da mal nombre a la improvisaci\u00f3n. Two Pale Boys est\u00e1n comprometidos en la &#8216;generaci\u00f3n espont\u00e1nea de canciones&#8217; (&#8230;). Los m\u00fasicos tienen tiempo de sobra para organizarse, brindar lo bueno (estructura, foco, dinamismo&#8230; poes\u00eda, visi\u00f3n y pasi\u00f3n) y evitar lo malo (tedio, indulgencia y predictibilidad)\u00bb. Ya ven: frente a esto, Turbonegro s\u00f3lo son capaces de escribir sobre sexo anal y preservativos usados. A pasarlo bien, Ciro.<\/p>\n<p><strong>Actualizado:<\/strong> a toro pasado -y esta expresi\u00f3n le va que ni pintada a un tipo tan grand\u00f3n como Thomas-, me veo obligado a rectificar. El concierto ha sido muy bueno, pero adem\u00e1s ha estado divertid\u00edsimo. Ha habido carcajadas y todo, se lo juro.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Este s\u00e1bado, a los evadidos nos toca dividirnos. El compa\u00f1ero Galante anunci\u00f3 con tiempo su prop\u00f3sito de acudir a Santana 27 para el concierto deTurbonegro, \u00ablos Village People del punk noruego\u00bb. A m\u00ed, aunque estoy convencido de que lo pasar\u00e9 peor, me llama m\u00e1s bajar a Bilborock para ver a David Thomas &#038; [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,602,701,1946,2311,3105],"class_list":["post-71","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-conciertos","tag-david-thomas-two-pale-boys","tag-mem","tag-pere-ubu","tag-turbonegro"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/71\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=71"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=71"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}