{"id":706,"date":"2009-09-28T11:31:00","date_gmt":"2009-09-28T11:31:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=706"},"modified":"2009-09-28T11:31:00","modified_gmt":"2009-09-28T11:31:00","slug":"un-aire-moderno","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/09\/28\/un-aire-moderno\/","title":{"rendered":"Un aire moderno"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Kim Ann Foxman, de Hercules And Love Affair\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"545\" height=\"409\" \/><\/p>\n<p>No se ofendan, pero Bilbao no es precisamente el para\u00edso de la modernidad musical. Hay muchos conciertos, s\u00ed, pero lo que manda en las agendas son las glorias viejas e incluso resucitadas, los artistas con ra\u00edces y las bandas actuales que suenan como podr\u00edan haberlo hecho en 1969 o en 1979. Bilbao es rockista y tradicionalista, pero mucho, e incluso dir\u00eda que tambi\u00e9n es m\u00e1s vanguardista que contempor\u00e1neo, aunque eso suene un poco parad\u00f3jico: resulta m\u00e1s f\u00e1cil pillar a alg\u00fan explorador de paisajes postindustriales que a todos esos grupetes que salen siempre mencionados en los blogs de Madrid y Barcelona.<\/p>\n<p>Por eso me ha llamado la atenci\u00f3n que en el futuro pr\u00f3ximo vayan a venir por aqu\u00ed un par de esos nombres pujantes. El m\u00e9rito es de Fever, un club al que jam\u00e1s voy \u2013no son horas, no son edades\u2013 pero que me parece un oasis, o m\u00e1s bien un inesperado g\u00e9iser en medio del p\u00e1ramo. La semana que viene anuncian a Kim Ann Foxman, la chica de Hercules And Love Affair que en su momento muchos confundieron con un chico (\u00bfo era al rev\u00e9s?) y que tienen en la foto de arriba. Y en noviembre han programado a The Pains Of Being Pure At Heart, grupo neoyorquino que ha conseguido una notable repercusi\u00f3n a pesar de ese nombre kilom\u00e9trico con dos preposiciones. Si a todo esto sumamos la variopinta troupe de Billie The Vision &#038; The Dancers, que estar\u00e1n en noviembre en la Rock Star Live, y los franceses Zombie Zombie el 12 de octubre en L\u2019Mono, esto empieza a parecer el siglo XXI.<\/p>\n<p>Les cuelgo el chul\u00edsimo v\u00eddeo de <em>Driving This Road Until Death Sets You Free<\/em>, de Zombie Zombie. Aunque, ahora que vuelvo a escucharla, en realidad esta canci\u00f3n tambi\u00e9n suena un poco a 1971.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/rT7AH4JyuNs&#038;hl=es&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/rT7AH4JyuNs&#038;hl=es&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No se ofendan, pero Bilbao no es precisamente el para\u00edso de la modernidad musical. Hay muchos conciertos, s\u00ed, pero lo que manda en las agendas son las glorias viejas e incluso resucitadas, los artistas con ra\u00edces y las bandas actuales que suenan como podr\u00edan haberlo hecho en 1969 o en 1979. Bilbao es rockista y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,602,1590,2967,3288],"class_list":["post-706","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-conciertos","tag-kim-ann-foxman","tag-the-pains-of-being-pure-at-heart","tag-zombie-zombie"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}