{"id":686,"date":"2009-08-14T11:29:00","date_gmt":"2009-08-14T11:29:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=686"},"modified":"2009-08-14T11:29:00","modified_gmt":"2009-08-14T11:29:00","slug":"cancion-la-semana-vaya-con-dios","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/08\/14\/cancion-la-semana-vaya-con-dios\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Vaya con Dios&#039;"},"content":{"rendered":"<p>Les Paul, que muri\u00f3 ayer a los 94 a\u00f1os, fue una figura clave en la creaci\u00f3n y el desarrollo de la guitarra el\u00e9ctrica. Un servidor nunca ha estado muy interesado por los modelos de guitarra ni por los entresijos t\u00e9cnicos de todo este asunto \u2013como me dijo ayer el <a id=\"link_0\" title=\"http:\/\/blogs.elcorreodigital.com\/punos-fuera\" href=\"..\/punos-fuera\">compa\u00f1ero Wu-Fei Chang<\/a> con una siniestra risita rob\u00f3tica, eso se debe a que nunca he sido heavy\u2013, pero la aportaci\u00f3n de Lester William Polsfuss es tan monumental que resulta casi obligado rendirle tributo: a \u00e9l se deben, aparte de la g\u00e9nesis del propio instrumento \u2013en competencia con Leo Fender\u2013, innovaciones como la grabaci\u00f3n por pistas o los efectos m\u00e1s importantes de guitarra, y eso sin meternos siquiera en harina puramente interpretativa. \u201cSin Les Paul, generaciones de gamberretes pasajeros como nosotros estar\u00edamos en la c\u00e1rcel o limpiando v\u00e1teres\u201d, ha dicho Keith Richards.<\/p>\n<p>Me van a permitir que, sin tener ninguna fe en un m\u00e1s all\u00e1, le despida con su versi\u00f3n de <em>Vaya con Dios<\/em> junto a Mary Ford, todo un superventas en 1953.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/pQ6H68AcvQE&#038;hl=es&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/pQ6H68AcvQE&#038;hl=es&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Les Paul, que muri\u00f3 ayer a los 94 a\u00f1os, fue una figura clave en la creaci\u00f3n y el desarrollo de la guitarra el\u00e9ctrica. Un servidor nunca ha estado muy interesado por los modelos de guitarra ni por los entresijos t\u00e9cnicos de todo este asunto \u2013como me dijo ayer el compa\u00f1ero Wu-Fei Chang con una siniestra [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1724,1921,2198],"class_list":["post-686","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-les-paul","tag-mary-ford","tag-obituarios"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}