{"id":675,"date":"2009-07-23T10:13:00","date_gmt":"2009-07-23T10:13:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=675"},"modified":"2009-07-23T10:13:00","modified_gmt":"2009-07-23T10:13:00","slug":"la-etiqueta-del-aplauso","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/07\/23\/la-etiqueta-del-aplauso\/","title":{"rendered":"La etiqueta del aplauso"},"content":{"rendered":"<p>En los medios brit\u00e1nicos se ha abierto un debate sobre un tema que siempre me ha fascinado: la m\u00fasica cl\u00e1sica y los aplausos. En el rock no existe ning\u00fan problema, claro, porque uno aplaude, vocea, silba, abuchea y hace el simio cuando le viene en gana, pero, en el mundo de los sonidos llamados <em>cultos<\/em>, la reacci\u00f3n del p\u00fablico se ha codificado hasta un extremo en el que pr\u00e1cticamente se desnaturaliza. Porque el aplauso es simplemente el medio que tienen los espectadores para comunicar al int\u00e9rprete que les gusta lo que han escuchado, \u00bfno? Y, sin embargo, en la m\u00fasica cl\u00e1sica se mira con reprobaci\u00f3n y desd\u00e9n a todo aquel que, por ignorancia o despiste, aplaude entre dos movimientos de la misma obra, aun cuando a veces el final de uno de esos segmentos invita claramente a una reacci\u00f3n jubilosa. Y esto lleva al curioso fen\u00f3meno complementario: parece existir una especie de competici\u00f3n entre algunos aficionados, llam\u00e9mosles as\u00ed, para identificar sin error el final de una obra y aplaudir en el mism\u00edsimo momento en que se desvanece la \u00faltima nota. Incluso a m\u00ed, que no frecuento muchos conciertos de m\u00fasica cl\u00e1sica, me ha sorprendido a veces la presteza con que la gente rompe a aplaudir cuando los m\u00fasicos todav\u00eda est\u00e1n en tensi\u00f3n, inmersos en lo que acaban de tocar.<\/p>\n<p>Como <a id=\"link_0\" title=\"http:\/\/news.bbc.co.uk\/2\/hi\/uk_news\/magazine\/8160543.stm\" href=\"http:\/\/news.bbc.co.uk\/2\/hi\/uk_news\/magazine\/8160543.stm\" rel=\"external nofollow\">resume la BBC<\/a>, la actual controversia comenz\u00f3 cuando el responsable de la secci\u00f3n de m\u00fasica cl\u00e1sica de la revista <em>Time Out<\/em> dirigi\u00f3 una carta al &#8216;hombre de aplausos ruidosos que se sienta detr\u00e1s de m\u00ed en los conciertos&#8217;, criticando esa prontitud antinatural cuyo \u00fanico objetivo parece ser el de demostrar un conocimiento detallado de la pieza: &#8220;La \u00faltima nota no es el final de la m\u00fasica, el silencio completa la m\u00fasica&#8221;, dice Jonathan Lennie, adem\u00e1s de citar obras como la novena de Mahler o el ciclo <em>Winterreise <\/em>de Schubert que exigen esos segundos de transici\u00f3n entre dos mundos. Lo que ocurre es que el debate tambi\u00e9n ha puesto sobre la mesa la otra obsesi\u00f3n que les comentaba, el veto al aplauso entre movimientos, y un desfile de expertos est\u00e1 puntualizando que ese silencio inquebrantable es una costumbre relativamente moderna: en tiempos de Brahms o Mozart lo normal era aplaudir en esos par\u00e9ntesis y, de hecho, a algunos compositores no les hac\u00eda nada de gracia que el p\u00fablico se quedase pasmado. El eslogan de &#8216;es s\u00f3lo rock and roll&#8217; se puede aplicar a tantas cosas que se toman demasiado en serio&#8230;<\/p>\n<p>Les dejo con Dietrich Fischer-Dieskau y la \u00faltima canci\u00f3n del ciclo <em>Winterreise<\/em>, <em>El hombre de la zanfona<\/em>, una de mis piezas cl\u00e1sicas favoritas (y lo digo como si supiera, je, je&#8230;). Aplaudan si quieren, aunque me parece que, ciertamente, es una m\u00fasica que se prolonga m\u00e1s all\u00e1 de lo que dura su sonido.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/DPOw0AyH1qA&#038;hl=es&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/DPOw0AyH1qA&#038;hl=es&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En los medios brit\u00e1nicos se ha abierto un debate sobre un tema que siempre me ha fascinado: la m\u00fasica cl\u00e1sica y los aplausos. En el rock no existe ning\u00fan problema, claro, porque uno aplaude, vocea, silba, abuchea y hace el simio cuando le viene en gana, pero, en el mundo de los sonidos llamados cultos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1702,2080,2419,2606],"class_list":["post-675","post","type-post","status-publish","format-standard","hentry","category-musica","tag-lecturas","tag-musica-clasica","tag-protocolo","tag-schubert"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=675"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/675\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}