{"id":673,"date":"2009-07-18T19:10:00","date_gmt":"2009-07-18T19:10:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=673"},"modified":"2009-07-18T19:10:00","modified_gmt":"2009-07-18T19:10:00","slug":"cancion-la-semana-mehbooba-mehbooba","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/07\/18\/cancion-la-semana-mehbooba-mehbooba\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Mehbooba, Mehbooba&#039;"},"content":{"rendered":"<p>Sin pretenderlo, cada cierto tiempo me engancho a alg\u00fan disco del <a id=\"link_2\" title=\"http:\/\/kronosquartet.org\" href=\"http:\/\/kronosquartet.org\/\" rel=\"external nofollow\">Kronos Quartet<\/a>, el cuarteto de cuerda estadounidense que lo mismo interpreta piezas de compositores contempor\u00e1neos de altos vuelos, que versiona a Hendrix o a Sigur R\u00f3s, que se sumerge en inesperadas m\u00fasicas asi\u00e1ticas, africanas o iberoamericanas. Su copiosa producci\u00f3n discogr\u00e1fica es tremendamente variada y dif\u00edcil de seguir (y, en ocasiones, de escuchar), pero siempre que dedico el tiempo suficiente a alguno de sus \u00e1lbumes suelo acabar entregado: me pas\u00f3, sobre todo, con el durillo <em>Black Angels<\/em> (150 pesetas pagu\u00e9 por el vinilo en una tienda de saldos), con el peculiar <em>Early Music<\/em> (donde barajan composiciones medievales y renacentistas con obras del siglo XX) y, sobre todo, con el divertid\u00edsimo e imprescindible <em>You&#8217;ve Stolen My Heart<\/em> que grabaron junto a la diva india Asha Bhosle, uno de los discos m\u00e1s sorprendentes de los <a id=\"link_3\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2005\/12\/28\/cinco-2005\" href=\"..\/evadidos\/2005\/12\/28\/cinco-2005\">\u00faltimos a\u00f1os<\/a>. Hoy ten\u00eda intenci\u00f3n de colgarles alg\u00fan corte de su nuevo lanzamiento, <em>Floodplain<\/em>, que les lleva a lugares como Egipto, Azerbaiy\u00e1n o Serbia (pueden catarlo <a id=\"link_0\" title=\"http:\/\/kronosquartet.org\/player\/browser.html\" href=\"http:\/\/kronosquartet.org\/player\/browser.html\" rel=\"external nofollow\">aqu\u00ed<\/a>), pero durante la b\u00fasqueda me he topado con este <em>Mehbooba, Mehbooba<\/em>, uno de los <a id=\"link_1\" title=\" http:\/\/www.youtube.com\/watch?v=SHYvwZ3v_8Y\" href=\"http:\/\/www.youtube.com\/watch?v=SHYvwZ3v_8Y\" rel=\"external nofollow\">cl\u00e1sicos bollywoodienses<\/a> <em> <\/em>incluidos en <em>You&#8217;ve Stolen My Heart<\/em>, interpretado en directo en compa\u00f1\u00eda de la int\u00e9rprete china de pipa Wu Man. Y no me he podido resistir.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/-0uaI1cID9Y&#038;hl=es&#038;fs=1&#038;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/-0uaI1cID9Y&#038;hl=es&#038;fs=1&#038;\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Sin pretenderlo, cada cierto tiempo me engancho a alg\u00fan disco del Kronos Quartet, el cuarteto de cuerda estadounidense que lo mismo interpreta piezas de compositores contempor\u00e1neos de altos vuelos, que versiona a Hendrix o a Sigur R\u00f3s, que se sumerge en inesperadas m\u00fasicas asi\u00e1ticas, africanas o iberoamericanas. Su copiosa producci\u00f3n discogr\u00e1fica es tremendamente variada y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[390,461,1618,3247],"class_list":["post-673","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bollywood","tag-cancion-de-la-semana","tag-kronos-quartet","tag-wu-man"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=673"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/673\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}