{"id":660,"date":"2009-05-17T21:20:00","date_gmt":"2009-05-17T21:20:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=660"},"modified":"2009-05-17T21:20:00","modified_gmt":"2009-05-17T21:20:00","slug":"la-noche-fue-ella","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/05\/17\/la-noche-fue-ella\/","title":{"rendered":"La noche no fue para ella"},"content":{"rendered":"<p>A m\u00ed me da pena Soraya. Me dan pena muchos de estos artistas salidos de concursos, porque tengo la sensaci\u00f3n de que verdaderamente se creen las cosas: est\u00e1n convencidos de que las canciones que les escriben son magistrales, de que el vestuario que les dise\u00f1an es chic, de que el concepto escenogr\u00e1fico que les preparan es lo m\u00e1s. Lo defienden todo con determinaci\u00f3n y mucho oficio y, de vez en cuando, se pegan un batacazo como <a id=\"link_0\" title=\"http:\/\/www.eurovision.tv\/event\/scoreboard?event=1482\" href=\"http:\/\/www.eurovision.tv\/event\/scoreboard?event=1482\" rel=\"external nofollow\">el de ayer<\/a>. Todo era falso, claro: la canci\u00f3n parec\u00eda confeccionada con alg\u00fan programa autom\u00e1tico chungo para escribir temas eurovisivos, el famoso mono como de <em>body painting<\/em> era cuestionable por delante y catastr\u00f3fico por detr\u00e1s, el rollo escenogr\u00e1fico qued\u00f3 como mucho decentillo&#8230; De todas formas, yo s\u00f3lo rogar\u00eda a los responsables de todo esto que, si nos empe\u00f1amos en mandar canciones con la letra o parte de la letra en ingl\u00e9s, se las encarguemos a alguien capaz de articular pensamientos m\u00e1s complejos que &#8220;come on and shake me&#8221;. Please, please, please.<\/p>\n<p>En cualquier caso, lo de Eurovisi\u00f3n no tiene remedio. Se ha solucionado en parte el problema de que los pa\u00edses amigos se voten entre ellos (aunque Soraya deber\u00eda obsequiar a los andorranos con un par de galas gratis), pero ahora ha surgido un h\u00e1ndicap todav\u00eda m\u00e1s grave: \u00a1\u00a1\u00a1todos votan al mismo!!! Porque, vamos, la propuesta de Noruega estaba bien, el hobbit que la cantaba ca\u00eda muy simp\u00e1tico, pero tampoco era como para despertar tal unanimidad en esa gran Europa que va de Islandia a Israel pasando por Azerbaiy\u00e1n. \u00bfNadie ha aventurado todav\u00eda que tras este triunfo arrollador se esconde alguna conspiraci\u00f3n siniestra, alguna preselecci\u00f3n secreta? Porque yo me apunto a esa tesis sin dudarlo.<\/p>\n<p>En mi clasificaci\u00f3n personal ganaban por segundo a\u00f1o consecutivo los franceses, los \u00fanicos que se atreven a llevar m\u00fasica de verdad. Y por detr\u00e1s de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Patricia_Kaas\" target=\"_blank\" rel=\"external nofollow\">Patricia Kaas<\/a>, cuya canci\u00f3n les cuelgo abajo, quedaban los alegres balcanismos de Moldavia y las elfas et\u00e9reas de Estonia (vaya, parece que andaba por all\u00ed la Tierra Media en pleno). Pero tambi\u00e9n me gustaban el lituano del piano, que empat\u00f3 con Soraya en el pen\u00faltimo puesto, y los frikis finlandeses de turno, que acabaron los \u00faltimos, as\u00ed que me temo que no soy qui\u00e9n para dar consejos a Soraya ni a nadie. Adem\u00e1s, lo mismo la enviamos con una obra maestra, con un atuendo de diez y con una escenograf\u00eda abracadabrante y queda igual de mal, as\u00ed que para qu\u00e9 darle vueltas.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"560\" height=\"340\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/h55rwuoN5I8&#038;hl=es&#038;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"560\" height=\"340\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/h55rwuoN5I8&#038;hl=es&#038;fs=1\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A m\u00ed me da pena Soraya. Me dan pena muchos de estos artistas salidos de concursos, porque tengo la sensaci\u00f3n de que verdaderamente se creen las cosas: est\u00e1n convencidos de que las canciones que les escriben son magistrales, de que el vestuario que les dise\u00f1an es chic, de que el concepto escenogr\u00e1fico que les preparan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[966,2282,2718],"class_list":["post-660","post","type-post","status-publish","format-standard","hentry","category-musica","tag-eurovision","tag-patricia-kaas","tag-soraya"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=660"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/660\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}