{"id":628,"date":"2009-02-25T19:34:00","date_gmt":"2009-02-25T19:34:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=628"},"modified":"2009-02-25T19:34:00","modified_gmt":"2009-02-25T19:34:00","slug":"spiderman-el-horizonte","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/02\/25\/spiderman-el-horizonte\/","title":{"rendered":"Spiderman en el horizonte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" style=\"width: 590px; height: 393px;\" title=\"U2\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"720\" height=\"479\" \/>\u00bfQu\u00e9, est\u00e1n preparados para U2? El grupo irland\u00e9s edita la semana que viene su nuevo \u00e1lbum, <em>No Line On The Horizon<\/em>, que <a id=\"link_0\" title=\"http:\/\/www.spotify.com\/go\/20090223-u2-excl-preview-rtve\" href=\"http:\/\/www.spotify.com\/go\/20090223-u2-excl-preview-rtve\" rel=\"external nofollow\">ya se puede escuchar enterito<\/a> a trav\u00e9s de Spotify (<a id=\"link_1\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2009\/1\/21\/futurismo-ahora-mismo\" href=\"..\/evadidos\/2009\/1\/21\/futurismo-ahora-mismo\">\u00bfrecuerdan?<\/a>), y la maquinaria promocional se ha puesto en marcha: durante un tiempo volveremos a tener a Bono \u2013y sus muchachos, pero sobre todo a Bono\u2013 hasta en la sopa, porque ya se sabe que los medios amplifican hasta la extenuaci\u00f3n el impacto de determinados artistas. Yo no he o\u00eddo a\u00fan el disco, pero me cuentan quienes s\u00ed lo han hecho que U2 vuelven a ponerse modernetes y un poco sint\u00e9ticos, como en los 90. Tambi\u00e9n me aseguran, y no hablo de gente sospechosa de <em>bonismo<\/em>, que el disco contiene dos o tres temazos incontestables. Porque U2 podr\u00e1n caer mejor o peor, pero malos no son.<\/p>\n<p>La curiosa noticia de hoy, que supongo formar\u00e1 parte de esa imponente maquinaria promocional, es que Bono y The Edge est\u00e1n escribiendo canciones para un musical que se estrenar\u00e1 en febrero de 2010. \u00bfY sobre qu\u00e9?, se preguntar\u00e1n ustedes. \u00bfSobre el hambre y la injusticia? \u00bfSobre el exterminio de alg\u00fan olvidado pueblo ind\u00edgena? \u00bfAcaso sobre la hermandad de los hombres de todo credo y condici\u00f3n? Pues no, la cosa va&#8230; estooo&#8230; sobre Spiderman. Se titula <em>Turn Off The Dark<\/em>, algo as\u00ed como <em>Apaga la oscuridad<\/em>, y al parecer es la producci\u00f3n m\u00e1s cara de toda la historia de Broadway. \u00bfEst\u00e1n preparados para m\u00e1s U2?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9, est\u00e1n preparados para U2? El grupo irland\u00e9s edita la semana que viene su nuevo \u00e1lbum, No Line On The Horizon, que ya se puede escuchar enterito a trav\u00e9s de Spotify (\u00bfrecuerdan?), y la maquinaria promocional se ha puesto en marcha: durante un tiempo volveremos a tener a Bono \u2013y sus muchachos, pero sobre todo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,2734,3117],"class_list":["post-628","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-spiderman","tag-u2"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}