{"id":6269,"date":"2025-07-30T16:53:33","date_gmt":"2025-07-30T15:53:33","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=6269"},"modified":"2025-07-30T17:06:21","modified_gmt":"2025-07-30T16:06:21","slug":"cosecha-de-enlaces-de-cancer-moon-a-puro-relajo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2025\/07\/30\/cosecha-de-enlaces-de-cancer-moon-a-puro-relajo\/","title":{"rendered":"Cosecha de enlaces: de Cancer Moon a Puro Relajo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6272\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer-600x497.jpeg\" alt=\"\" width=\"560\" height=\"464\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer-600x497.jpeg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer-300x249.jpeg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer-150x124.jpeg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer-768x636.jpeg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2025\/07\/kylie-caganer.jpeg 1336w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Durante a\u00f1os tuve la sana costumbre de recopilar de vez en cuando por aqu\u00ed los enlaces a los temas sobre m\u00fasica que iba publicando en el peri\u00f3dico <em>de verdad<\/em>, a modo de puentecito entre el trabajo real y estos desahogos blogueros. \u00bfY a santo de qu\u00e9 lo retomo despu\u00e9s de una ausencia tan larga, en mitad de este mausoleo en ruinas que es el blog? Pues la culpa es de los festivales, el Azkena y el Bilbao BBK Live: esos d\u00edas se me acumulan los asuntos musicales y me he dicho que es una pena no darles un poquillo de eco aqu\u00ed, con lo que resuena el eco en el vac\u00edo. La mayor\u00eda estar\u00e1n solo para suscriptores, pero, dependiendo de la modalidad, a lo mejor pod\u00e9is leerlos.<\/p>\n<p>Ya puesto, me he remontado a finales del a\u00f1o pasado: tenemos por ah\u00ed la reedici\u00f3n del fundamental <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/reeditan-moor-room-obra-definitiva-bilbainos-cancer-20241120002801-nt.html\" rel=\"external nofollow\"><em>Moor Room<\/em> de Cancer Moon<\/a>, la entrada en el armario de <a href=\"https:\/\/www.elcorreo.com\/sociedad\/gran-himno-gay-village-people-hetero-20241206001853-nt.html\" rel=\"external nofollow\"><em>YMCA<\/em><\/a>, la <a href=\"https:\/\/www.elcorreo.com\/bizkaia\/memoria-tribus-urbanas-bizkaia-hoy-fortin-resistencia-20250119190716-nt.html\" rel=\"external nofollow\">memoria de las tribus urbanas<\/a> de Bilbao, el obituario del artista y dinamizador <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/muere-anos-miguel-garcia-figura-central-musicas-20250107132640-nt.html\" rel=\"external nofollow\">Miguel A. Garc\u00eda<\/a>, el debut en solitario del <em>arkestral<\/em> Marshall Allen <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/musico-debuta-solitario-100-anos-20250205001913-nt.html\" rel=\"external nofollow\">a los 100 a\u00f1os<\/a>, una celebraci\u00f3n psic\u00f3tica de San Valent\u00edn con <a href=\"https:\/\/www.elcorreo.com\/culturas\/territorios\/ivy-lux-amor-trastorno-psicotico-compartido-20250208173034-nt.html\" rel=\"external nofollow\">Ivy y Lux<\/a>, la presentaci\u00f3n de la dulce oscuridad de <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/verde-prato-atrae-partir-dulzura-rozar-oscuro-20250311093902-nt.html\" rel=\"external nofollow\">Verde Prato<\/a>, la <a href=\"https:\/\/www.elcorreo.com\/culturas\/territorios\/solo-festivales-vive-20250315121751-nt.html\" rel=\"external nofollow\">cumbre de m\u00fasicos<\/a> en Bilborock para celebrar el n\u00famero 1.500 del cuadernillo <em>Territorios<\/em>, la panor\u00e1mica de los <a href=\"https:\/\/www.elcorreo.com\/culturas\/territorios\/getxo-vitoria-donostia-gran-trio-jazz-20250621171413-nt.html\" rel=\"external nofollow\">festivales vascos de jazz<\/a> o el frente vanguardista de <a href=\"https:\/\/www.elcorreo.com\/culturas\/musica\/karpenter-intensidades-ortega-vanguardia-musical-sigue-explorando-20250610004017-nt.html\" rel=\"external nofollow\">Al Karpenter e Intensidades Ortega<\/a>. Ya en territorio Azkena, podemos picotear el <a href=\"https:\/\/www.diariovasco.com\/culturas\/musica\/one-two-three-arf-busca-concierto-20250619071643-nt.html\" rel=\"external nofollow\">repaso al cartel<\/a>, la <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/dan-cuatro-horas-azkena-mejor-festival-europa-20250619222400-nt.html\" rel=\"external nofollow\">cr\u00f3nica diurna<\/a> de la primera jornada, el abrazo el\u00e9ctrico de <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/dinosaur-dejan-abrazar-electricidad-20250620073046-nt.html\" rel=\"external nofollow\">Dinosaur Jr.<\/a>, el <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/trogloditas-luchadores-salvajes-general-20250619005333-nt.html\" rel=\"external nofollow\">vistazo a Trashville<\/a> con las gafas de Juanito Wau, el perfil de <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/john-fogerty-guardian-esencias-rock-americano-20250619001919-nt.html\" rel=\"external nofollow\">John Fogerty<\/a> y la rese\u00f1a de su <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/john-fogerty-encadena-clasicos-celebracion-carrera-20250621071715-nt.html\" rel=\"external nofollow\">gran celebraci\u00f3n<\/a> sobre el escenario, un r\u00e9por sobre <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/manic-street-preachers-companero-ausente-siempre-ahi-20250619011051-nt.html\" rel=\"external nofollow\">la desaparici\u00f3n<\/a> del <em>manic<\/em> Richey, la batalla entre <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/manic-street-preachers-estribillos-pueden-lluvia-20250622082153-nt.html\" rel=\"external nofollow\">estribillos y lluvia<\/a> del concierto de los galeses, el pub que mont\u00f3 <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/virgen-blanca-pub-suena-rock-and-roll-20250620153359-nt.html\" rel=\"external nofollow\">Laurie Wright<\/a> en la Virgen Blanca, el viaje en el tiempo de <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/richard-hawley-lleva-azkena-viaje-tiempo-20250621213824-nt.html\" rel=\"external nofollow\">Richard Hawley<\/a> y los sermones de ira y destrucci\u00f3n de <a href=\"https:\/\/www.elcorreo.com\/festivales\/azkena-rock\/sermones-destruccion-ira-john-lydon-plena-forma-20250620231244-nt.html\" rel=\"external nofollow\">PiL<\/a>. Y, si saltamos al BBK Live, nos topamos tambi\u00e9n con la inevitable <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/california-croacia-monte-caramelo-emociones-cuatro-horas-20250710224211-nt.html\" rel=\"external nofollow\">cr\u00f3nica diurna<\/a> de la primera jornada, las lecciones del <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/pulp-bbk-live-20250710103742-nt.html\" rel=\"external nofollow\">profesor Jarvis<\/a> con Pulp, el <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/jessica-pratt-logra-milagro-publico-silencioso-20250711203351-nt.html\" rel=\"external nofollow\">milagro silencioso<\/a> de Jessica Pratt, el agradecido macarreo de <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/amyl-and-the-sniffers-abran-paso-guitarras-20250711230450-nt.html\" rel=\"external nofollow\">Amyl and the Sniffers<\/a>, las charlas con <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/kylie-reina-diskobetas-20250712222541-nt.html\" rel=\"external nofollow\">fans de Kylie Minogue<\/a> (de ah\u00ed viene su desconcertante foto con caganer independentista) y su concierto en <a href=\"https:\/\/www.elcorreo.com\/festivales\/bilbao-bbk-live\/kylie-minogue-bbk-live-20250712112326-nt.html\" rel=\"external nofollow\">la discoteca de los sue\u00f1os<\/a>. Y acabamos, ya que estamos en verano, de verbena con el euskalmex de <a href=\"https:\/\/www.elcorreo.com\/vivir\/ocio\/parranda-puro-relajo-reyes-euskalmex-20250720191258-ntrc.html\" rel=\"external nofollow\">Puro Relajo<\/a>, cuyo nombre es un espl\u00e9ndido plan de vacaciones.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Durante a\u00f1os tuve la sana costumbre de recopilar de vez en cuando por aqu\u00ed los enlaces a los temas sobre m\u00fasica que iba publicando en el peri\u00f3dico de verdad, a modo de puentecito entre el trabajo real y estos desahogos blogueros. \u00bfY a santo de qu\u00e9 lo retomo despu\u00e9s de una ausencia tan larga, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[244,328,460,4105,1702,4104],"class_list":["post-6269","post","type-post","status-publish","format-standard","hentry","category-musica","tag-azkena-rock-festival","tag-bilbao-bbk-live","tag-cancer-moon","tag-kylie-minogue","tag-lecturas","tag-puro-relajo"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=6269"}],"version-history":[{"count":4,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6269\/revisions"}],"predecessor-version":[{"id":6274,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6269\/revisions\/6274"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=6269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=6269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=6269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}