{"id":6133,"date":"2024-12-14T09:17:36","date_gmt":"2024-12-14T08:17:36","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=6133"},"modified":"2024-12-14T09:18:37","modified_gmt":"2024-12-14T08:18:37","slug":"cancion-de-la-semana-krishna-krishna","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2024\/12\/14\/cancion-de-la-semana-krishna-krishna\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Krishna Krishna&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6134\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane-600x407.jpg\" alt=\"\" width=\"560\" height=\"380\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane-600x407.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane-300x203.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane-150x102.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane-768x521.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/12\/Alice-Coltrane.jpg 1500w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En estos d\u00edas retrospectivos de final de a\u00f1o, quer\u00eda abrir un huequecito a un par de m\u00fasicas m\u00e1s antiguas que no hab\u00eda escuchado hasta 2024 y que se han instalado entre mis favoritas. De una ya hablamos por aqu\u00ed, porque fue canci\u00f3n de la semana y (me lo confirm\u00f3 el temible <em>Wrapped<\/em> de Spotify) ha sido uno de mis tres temas m\u00e1s escuchados del a\u00f1o: me refiero a la maravillosa <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2024\/01\/14\/cancion-de-la-semana-next-time-might-be-your-time\/\"><em>Next Time Might Be Your Time<\/em><\/a> de <em>Blue<\/em> Gene Tyranny, ocho minutos de belleza y disfrute que deber\u00edan tener much\u00edsima m\u00e1s fama. Esa ser\u00eda mi canci\u00f3n inactual del a\u00f1o.<\/p>\n<p>Y mi \u00e1lbum inactual del a\u00f1o nos lleva a una gigante como <a href=\"https:\/\/www.alicecoltrane.com\" rel=\"external nofollow\">Alice Coltrane<\/a>, pianista y arpista que durante alg\u00fan tiempo qued\u00f3 a la sombra de su marido, John, pero que en los \u00faltimos tiempos ha sido objeto de una reevaluaci\u00f3n rendida y merecid\u00edsima. Yo conoc\u00eda relativamente lo que podr\u00edamos llamar el n\u00facleo de su producci\u00f3n, ese jazz espiritual, radicalmente libre pero a la vez accesible, emancipado de las ataduras de la tradici\u00f3n pero tambi\u00e9n de la latosa obligaci\u00f3n de ubicarse siempre en la proa de la vanguardia. Temas como <a href=\"https:\/\/www.youtube.com\/watch?v=w0O9L7KXkC0\" rel=\"external nofollow\"><em>Journey In Satchidananda<\/em><\/a> dan una buena idea de ese equilibrio natural entre lo estimulante y lo accesible. Pero lo que no conoc\u00eda hasta este a\u00f1o (m\u00e1s concretamente hasta que lo comparti\u00f3 en redes Daniel Casta\u00f1o, de <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/04\/11\/canciones-de-la-semana-baile-sin-dientes-y-el-futuro-es-anormal\/\">The Berlangas<\/a>) era <em>Turiya Sings<\/em> y, m\u00e1s en concreto, su versi\u00f3n m\u00e1s despojada, <em>Kirtan: Turiya Sings<\/em>.<\/p>\n<p>Alice era maestra hinduista con el nombre de Swamini Turiyasangitananda, del que Turiya es una versi\u00f3n familiar. A mitad de los 70 fund\u00f3 un centro v\u00e9dico en California y en 1981 grab\u00f3 algunos himnos devocionales en s\u00e1nscrito para sus estudiantes, que public\u00f3 de manera privada en versi\u00f3n casete. Ah\u00ed Alice, Turiya, canta acompa\u00f1\u00e1ndose al \u00f3rgano Wurlitzer y envuelta en sintetizadores y cuerdas que se a\u00f1adieron despu\u00e9s, pero en 2004, tres a\u00f1os despu\u00e9s del fallecimiento de la artista, su hijo Ravi encontr\u00f3 una mezcla desnuda en la que solo estaban la voz y el \u00f3rgano. Esta versi\u00f3n esencial y austera se public\u00f3 en 2021 con el t\u00edtulo de <em>Kirtan: Turiya Sings<\/em>, un disco hipn\u00f3tico que, aunque no soy mucho de esas cosas, s\u00ed que tiene algo de curativo o, al menos, de reconfortante, como si te fuese reordenando las piezas de ese puzle mental que todos tenemos bastante desbaratado. Es m\u00fasica que crea su propio espacio y su propio tiempo, que abre par\u00e9ntesis, levanta refugios e infunde en el oyente un talante meditativo. Vamos, es lo contrario de tantas trivialidades que escuchamos a diario. Este <em>Krishna Krishna<\/em> es una buena muestra.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Hn36bzFZeg4?si=sKjiKwW8-XLcL1La\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; En estos d\u00edas retrospectivos de final de a\u00f1o, quer\u00eda abrir un huequecito a un par de m\u00fasicas m\u00e1s antiguas que no hab\u00eda escuchado hasta 2024 y que se han instalado entre mis favoritas. De una ya hablamos por aqu\u00ed, porque fue canci\u00f3n de la semana y (me lo confirm\u00f3 el temible Wrapped de Spotify) [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[4072,461,950,4073,1340],"class_list":["post-6133","post","type-post","status-publish","format-standard","hentry","category-musica","tag-alice-coltrane","tag-cancion-de-la-semana","tag-estados-unidos","tag-hinduismo","tag-india"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=6133"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6133\/revisions"}],"predecessor-version":[{"id":6137,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6133\/revisions\/6137"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=6133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=6133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=6133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}