{"id":611,"date":"2009-01-16T13:29:00","date_gmt":"2009-01-16T13:29:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=611"},"modified":"2009-01-16T13:29:00","modified_gmt":"2009-01-16T13:29:00","slug":"discos-efe-eme","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2009\/01\/16\/discos-efe-eme\/","title":{"rendered":"Discos en Efe Eme"},"content":{"rendered":"<p><img decoding=\"async\" id=\"img_0\" class=\"imgdcha\" style=\"width: 194px; height: 353px;\" title=\"Jos\u00e9 Mar\u00eda Guzm\u00e1n\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" \/>En la prensa musical siempre se agradece un poco de disidencia, porque si no parece que estamos leyendo distintos boletines de un Ministerio del Gusto. Pero, no s\u00e9 si se deber\u00e1 m\u00e1s a que ha cambiado el mundo o a que he cambiado yo, mi percepci\u00f3n de lo disidente se ha alterado por completo en doce o quince a\u00f1os: antes lo identificaba con una ruptura radical con el pasado y ahora, en cambio, creo que los aut\u00e9nticos rebeldes son los que defienden cierta perspectiva hist\u00f3rica, los que se toman la molestia de esforzarse para situar cada cosa en su lugar. Tengo la sensaci\u00f3n de que la modernidad a ultranza se ha vuelto doctrinaria, y por eso me parece m\u00e1s contestatario destacar en una revista a Jos\u00e9 Antonio Labordeta que a Little Boots. Lo que nos lleva a una de las pocas publicaciones capaces de dedicar un <a id=\"link_0\" title=\"http:\/\/www.efeeme.com\/revista\/revista_ficha.aspx?ids=2&#038;id=3238\" href=\"http:\/\/www.efeeme.com\/revista\/revista_ficha.aspx?ids=2&#038;id=3238\" rel=\"external nofollow\">hueco preeminente<\/a> al cantautor y ex diputado aragon\u00e9s: <em>Efe Eme<\/em>, de la que ya <a id=\"link_0\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2007\/1\/25\/efe-eme-pe-efe\" href=\"..\/evadidos\/2007\/1\/25\/efe-eme-pe-efe\">hemos hablado por aqu\u00ed<\/a>. Los t\u00edos han elegido un disco de Adriano Celentano como el mejor de 2008, recuperan a bandas olvidadas como Los Esqueletos, no pierden de vista a viejas glorias del pelo de Santiago Auser\u00f3n (hombre, yo tachar\u00eda muy a gusto a otros figurones, pero qu\u00e9 le vamos a hacer) y atienden mucho a esa descuidada <em>tercera v\u00eda<\/em> que equidista de lo alternativo y de lo comercial.<\/p>\n<p>En fin, lo que quer\u00eda decirles desde hace varias semanas es que <em>Efe Eme<\/em> est\u00e1 celebrando su d\u00e9cimo aniversario con una colecci\u00f3n de discos in\u00e9ditos descargables gratuitamente <a id=\"link_1\" title=\"http:\/\/www.efeeme.com\/descargas\/descargas.aspx?ids=7\" href=\"http:\/\/www.efeeme.com\/descargas\/descargas.aspx?ids=7\" rel=\"external nofollow\">desde su web<\/a>: el m\u00e1s reciente es un directo de Se\u00f1or Mostaza, pero hay tambi\u00e9n un \u00e1lbum completo de Jos\u00e9 Mar\u00eda Guzm\u00e1n (el de la foto, miembro de Cadillac y de C\u00e1novas, Rodrigo, Adolfo y, eso, Guzm\u00e1n), un ac\u00fastico de Ariel Rot (grabado parcialmente en Euskadi) y un ramillete de versiones y rarezas de Doctor Divago. Y que flipen sus amigos indies.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En la prensa musical siempre se agradece un poco de disidencia, porque si no parece que estamos leyendo distintos boletines de un Ministerio del Gusto. Pero, no s\u00e9 si se deber\u00e1 m\u00e1s a que ha cambiado el mundo o a que he cambiado yo, mi percepci\u00f3n de lo disidente se ha alterado por completo en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[201,735,791,857,1507,2506,2631],"class_list":["post-611","post","type-post","status-publish","format-standard","hentry","category-musica","tag-ariel-rot","tag-descargas-gratuitas","tag-doctor-divago","tag-efe-eme","tag-jose-maria-guzman","tag-revistas","tag-senor-mostaza"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}