{"id":6044,"date":"2024-06-30T09:02:25","date_gmt":"2024-06-30T08:02:25","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=6044"},"modified":"2024-06-30T09:02:25","modified_gmt":"2024-06-30T08:02:25","slug":"cancion-de-la-semana-action-painting","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2024\/06\/30\/cancion-de-la-semana-action-painting\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Action Painting&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-6045\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/06\/Perennial-600x400.jpg\" alt=\"\" width=\"560\" height=\"373\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/06\/Perennial-600x400.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/06\/Perennial-300x200.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/06\/Perennial-150x100.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/06\/Perennial.jpg 696w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La etiqueta art-punk siempre me ha resultado un poco antip\u00e1tica, aunque se la aplican (y a veces se la aplico) a bastantes grupos que me gustan mucho, desde The Fall y Wire hasta esos Marcel Wave que tuvimos por aqu\u00ed hace un par de semanas. Pero, en fin, supongo que con <a href=\"https:\/\/www.instagram.com\/perennialtheband\" rel=\"external nofollow\">Perennial<\/a> no hay otro remedio que recurrir a esa categor\u00eda, porque, aunque su sonido no tenga mucho que ver con esos referentes de la exploraci\u00f3n estil\u00edstica, ocurre que muchas de sus canciones m\u00e1s recientes van, s\u00ed, sobre arte. Su nuevo \u00e1lbum, el tercero, se titula <a href=\"https:\/\/perennialtheband.bandcamp.com\/album\/art-history\" rel=\"external nofollow\"><em>Art History<\/em><\/a> e incluso se permiten incluir un corte que han bautizado <em>Con a de abstracto<\/em> y que es, en fin, un instrumental bastante abstracto (y despu\u00e9s repiten la gracia con la be y el brutalismo). En su anterior EP, de febrero de este a\u00f1o, metieron canciones llamadas <em>Impressionism<\/em>, <em>Minimalism<\/em> y <em>Expressionism<\/em>.<\/p>\n<p>Pero bueno, m\u00e1s all\u00e1 de obsesiones, lo bueno del tr\u00edo de Connecticut, con formaci\u00f3n de guitarra-\u00f3rgano-bater\u00eda y bonitas camisetas a rayas, es que suena arrollador, con un rock garajero, acuciante, gozoso y entregado en el que a menudo se cuelan ecos sesenteros. En el disco se ventilan doce canciones en veinti\u00fan minutos, que es lo que suelen durar sus conciertos, y la verdad es que cualquiera de ellas me habr\u00eda valido para destacar en la secci\u00f3n: iba a tirar por la primera, una atropellada carrera de un minuto, pero al final me he inclinado por esta, <em>Action Painting<\/em>, que dura dos y muestra m\u00e1s matices de la banda. Vamos, que vienen a ser dos atropelladas carreras enlazadas por un interludio de respiro. Y adem\u00e1s tiene v\u00eddeo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Eyp4igpeleI?si=_GVCIe-t5L4-Aj33\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; La etiqueta art-punk siempre me ha resultado un poco antip\u00e1tica, aunque se la aplican (y a veces se la aplico) a bastantes grupos que me gustan mucho, desde The Fall y Wire hasta esos Marcel Wave que tuvimos por aqu\u00ed hace un par de semanas. Pero, en fin, supongo que con Perennial no hay [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,950,4049],"class_list":["post-6044","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-estados-unidos","tag-perennial"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=6044"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6044\/revisions"}],"predecessor-version":[{"id":6046,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/6044\/revisions\/6046"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=6044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=6044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=6044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}