{"id":5942,"date":"2024-02-23T13:44:50","date_gmt":"2024-02-23T12:44:50","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5942"},"modified":"2024-02-23T14:12:07","modified_gmt":"2024-02-23T13:12:07","slug":"cancion-de-la-semana-real-doll-time","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2024\/02\/23\/cancion-de-la-semana-real-doll-time\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Real Doll Time&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5943\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex-600x489.jpeg\" alt=\"\" width=\"560\" height=\"456\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex-600x489.jpeg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex-300x245.jpeg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex-150x122.jpeg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex-768x626.jpeg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2024\/02\/VR-Sex.jpeg 770w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Con eso de que, cuando llega la hora de los balances de fin de a\u00f1o, los responsables de la secci\u00f3n de Cultura nos suelen pedir a los m\u00e1s <em>musiqueros<\/em> que seleccionemos nuestro disco y nuestro concierto favoritos, me he acostumbrado a confeccionar un<em> hit parade<\/em> de los artistas a los que voy viendo en directo. Pues bien, mi lista del a\u00f1o pasado estuvo encabezada durante unos meses por esta gente que nos ocupa hoy, los californianos VR SEX, que en febrero de 2023 desencadenaron una poderos\u00edsima explosi\u00f3n de energ\u00eda en las dependencias bilba\u00ednas de Donations Project. Hay quien identifica el post-punk siniestrillo con languidez y afectaci\u00f3n, pero aquello fue un bolo arrollador, tremendamente f\u00edsico, que puso a bailar incluso a macetas como yo. Tuvieron que llegar unas leyendas como Godflesh para relegarlos al segundo puesto, pero llegu\u00e9 a plantearme un liderazgo ex aequo, como reconocimiento a dos manifestaciones radicalmente diversas de un mismo coraz\u00f3n oscuro.<\/p>\n<p>VR SEX (vamos, el <em>sexo en realidad virtual, <\/em>algo que no siempre da un resultado decoroso en los buscadores) es el proyecto de \u00abpost-punk psicod\u00e9lico\u00bb o \u00abpunk \u00e1cido\u00bb de Noel Skum, m\u00e1s conocido como Andrew Clinco e incluso como Deb Demure en su faceta de l\u00edder de Drab Majesty. Su intenci\u00f3n con VR Sex era canalizar sonidos m\u00e1s potentes, y quiz\u00e1 por eso la cosa ha acabado creciendo hasta convertirse en el intenso quinteto de hoy en d\u00eda. En marzo lanzan <a href=\"https:\/\/vrsex.bandcamp.com\/album\/hard-copy\" rel=\"external nofollow\">su nuevo \u00e1lbum<\/a>, un ramillete de canciones sobre \u00ablujuria retorcida, emociones baratas, dinero sucio, delincuentes condenados al fracaso y romance en ruinas\u00bb que, desde luego, promete mucho si lo juzgamos por el que fue su primer adelanto, este <em>Real Doll Time<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=3185755022\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=4241405419\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/vrsex.bandcamp.com\/album\/hard-copy\" rel=\"external nofollow\">Hard Copy by VR SEX<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Con eso de que, cuando llega la hora de los balances de fin de a\u00f1o, los responsables de la secci\u00f3n de Cultura nos suelen pedir a los m\u00e1s musiqueros que seleccionemos nuestro disco y nuestro concierto favoritos, me he acostumbrado a confeccionar un hit parade de los artistas a los que voy viendo en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[452,461,950,4028],"class_list":["post-5942","post","type-post","status-publish","format-standard","hentry","category-musica","tag-california","tag-cancion-de-la-semana","tag-estados-unidos","tag-vr-sex"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5942"}],"version-history":[{"count":6,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5942\/revisions"}],"predecessor-version":[{"id":5949,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5942\/revisions\/5949"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}