{"id":583,"date":"2008-11-08T21:12:00","date_gmt":"2008-11-08T21:12:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=583"},"modified":"2008-11-08T21:12:00","modified_gmt":"2008-11-08T21:12:00","slug":"mi-cancion-la-semana","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/11\/08\/mi-cancion-la-semana\/","title":{"rendered":"Canci\u00f3n de la semana: &#039;Social Competence&#039;"},"content":{"rendered":"<p>Esta semana he descubierto una canci\u00f3n que se public\u00f3 en abril. T\u00edrenme piedras si quieren, que eso no me averg\u00fcenza: en realidad, todas las semanas estoy descubriendo canciones que se publicaron hace treinta y cuarenta a\u00f1os. Lo que me descoloca un poco y me empuja a tristes meditaciones es que yo YA TEN\u00cdA esa canci\u00f3n desde abril: supongo que la descargu\u00e9 de alg\u00fan blog alegal y perverso, o que me la pas\u00f3 alg\u00fan amigo, o que ven\u00eda de regalo con los cereales de Auchan, pero el caso es que el tema de marras lleva siete meses en mi iTunes y mi iPod sin que yo, iDiota, haya sabido siquiera de su existencia. Qu\u00e9 tiempos.<\/p>\n<p>Seguro que se acuerdan de <em>Young Folks<\/em>, la canci\u00f3n con silbiditos del tr\u00edo sueco Peter Bjorn &#038; John que nos obligaron a escuchar hasta la extenuaci\u00f3n en la tele (era la sinton\u00eda de <em>Cuesti\u00f3n de sexo<\/em>, creo), en tonos de m\u00f3vil (aqu\u00ed, en el peri\u00f3dico, un compa\u00f1ero lo llevaba, y es curioso c\u00f3mo una melod\u00eda tan buenrollista puede abrir la sed de sangre con s\u00f3lo reproducirla diez veces seguidas) y en lugares p\u00fablicos en general. Pero, si han sido capaces de olvidar la experiencia, all\u00e1 ustedes: <a id=\"link_1\" title=\"http:\/\/www.youtube.com\/watch?v=LqjFKsZiQek\" href=\"http:\/\/www.youtube.com\/watch?v=LqjFKsZiQek\" rel=\"external nofollow\">pinchen aqu\u00ed<\/a> y se tirar\u00e1n silbando el resto de la jornada. En fin, yo pensaba que los chicos estos ser\u00edan un grupo como de mentira, asalariados de alg\u00fan Doctor Infierno del pop, pero resulta que son m\u00fasicos de verdad y llevan una d\u00e9cada en activo. Y ah\u00ed llego a mi canci\u00f3n de esta semana, <em>Social Competence<\/em>, que fue el single en solitario de uno de ellos, Peter Mor\u00e9n, y reafirma a estos tipos como campeones de la melod\u00eda pegadiza. Aqu\u00ed debajo tienen a Mor\u00e9n en un v\u00eddeo de la tele sueca, enfrentado a los elementos mientras interpreta la canci\u00f3n con guitarra y arm\u00f3nica. A ver si les gusta. Yo voy a ponerme a revisar m\u00e1s archivos con &#8216;cero reproducciones&#8217;, a ver si encuentro alg\u00fan otro tesorillo en el subsuelo del disco duro.<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"508\" height=\"315\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"quality\" value=\"high\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"src\" value=\"http:\/\/blogg.svt.se\/psl\/wordpress\/wp-content\/themes\/psl\/flash\/player-16-9.swf?movie_id=2164\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"508\" height=\"315\" type=\"application\/x-shockwave-flash\" src=\"\/\/blogg.svt.se\/psl\/wordpress\/wp-content\/themes\/psl\/flash\/player-16-9.swf?movie_id=2164\" quality=\"high\" allowFullScreen=\"true\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Esta semana he descubierto una canci\u00f3n que se public\u00f3 en abril. T\u00edrenme piedras si quieren, que eso no me averg\u00fcenza: en realidad, todas las semanas estoy descubriendo canciones que se publicaron hace treinta y cuarenta a\u00f1os. Lo que me descoloca un poco y me empuja a tristes meditaciones es que yo YA TEN\u00cdA esa canci\u00f3n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,2322,2327,2381,2477,2780],"class_list":["post-583","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-peter-bjorn-john","tag-peter-moren","tag-pop","tag-recomendados","tag-suecia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=583"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/583\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}