{"id":580,"date":"2008-09-30T13:18:00","date_gmt":"2008-09-30T13:18:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=580"},"modified":"2008-09-30T13:18:00","modified_gmt":"2008-09-30T13:18:00","slug":"magazine-segunda-epoca","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/09\/30\/magazine-segunda-epoca\/","title":{"rendered":"Magazine, segunda \u00e9poca"},"content":{"rendered":"<p>\u00daltimamente el rock parece haber ingresado en una extra\u00f1a dimensi\u00f3n atemporal. La m\u00fasica actual y la m\u00fasica del pasado conviven, o compiten, en mayor igualdad de condiciones que antes de Internet: todo est\u00e1 disponible y, con perd\u00f3n, todo es gratis, as\u00ed que el chaval que se aficiona a Wolfmother puede regalarse tambi\u00e9n a Led Zeppelin sin m\u00e1s esfuerzo que teclear y cliquear unas cuantas veces. De hecho, ni siquiera tiene que investigar para descubrirlos, porque seguramente se los recomendar\u00e1 <a id=\"link_0\" title=\"http:\/\/www.ipodnoticias.com\/2008\/09\/itunes-8-no-tan-genius.html\" href=\"http:\/\/www.ipodnoticias.com\/2008\/09\/itunes-8-no-tan-genius.html\" rel=\"external nofollow\">Genius<\/a>, o Last.fm, o cualquiera de esos misteriosos cerebros dedicados a deducir qu\u00e9 artistas nos encantar\u00edan si tuvi\u00e9semos tiempo de o\u00edrlos (en buena l\u00f3gica, ese proceso de ir escuchando sonidos cercanos a los que ya conocemos acabar\u00eda extendiendo nuestro gusto hasta abarcar la producci\u00f3n musical de toda la historia, pero lamentablemente moriremos antes). Para colmo, la rentabilidad de la m\u00fasica en directo en esta era de los <em>royalties <\/em>menguantes ha devuelto a la carretera a una inconcebible caterva de viejos rockeros, cuyo peso hist\u00f3rico suele aplastar a los nuevos artistas en el cartel de festivales y en muchas publicaciones del ramo. Parece que, de pronto, todo est\u00e1 sucediendo a la vez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgdcha\" title=\"Howard Devoto, de Buzzcocks y Magazine\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"240\" height=\"379\" \/>Como muestra de esta nueva costumbre de resucitar, ayer me enter\u00e9 de que se ha reunido uno de mis grupos favoritos, una banda tan ligada a un momento de la historia que me resulta incongruente que vuelvan a existir, aunque s\u00f3lo sea \u2013por ahora\u2013 para tres conciertos en Gran Breta\u00f1a. No son muy famosos, pero s\u00ed influyentes en ciertos \u00e1mbitos: <a id=\"link_1\" title=\"http:\/\/www.myspace.com\/magazineofficial\" href=\"http:\/\/www.myspace.com\/magazineofficial\" rel=\"external nofollow\">Magazine<\/a> nacieron en Manchester en el 77, cuando el primer cantante y l\u00edder de los Buzzcocks, Howard Devoto (en la fotillo), decidi\u00f3 que hab\u00eda quemado su etapa punk en un tiempo r\u00e9cord y se lanz\u00f3 a explorar nuevos territorios. El sonido de su nueva banda quiz\u00e1 fuese punk en esp\u00edritu, pero desde luego tambi\u00e9n ten\u00eda mucho que ver con estilos previos y opuestos al punk, como ese rock progresivo al que remit\u00eda Dave Formula con sus torres de teclados, y el tono intelectual y penumbroso de sus canciones les acercaba asimismo a sus primos los siniestros. Resulta significativo ver en qu\u00e9 otras bandas tocaron sus miembros \u2013Visage, Birthday Party, Siouxsie &#038; The Banshees\u2013 y qu\u00e9 artistas les han versionado, desde Morrissey hasta conjuntos de metal oscuro. \u00daltimamente, seguro que Genius y compa\u00f1\u00eda se han hartado de dar pistas sobre Magazine a los seguidores del revivalismo post punk que tanto se lleva.<\/p>\n<p>Lo habitual es recomendar su primer \u00e1lbum, <em>Real Life<\/em>, pero yo soy devoto \u2013je, je, ten\u00eda que usar la palabra\u2013 del segundo, el g\u00e9lido <em>Secondhand Daylight<\/em>. Les dejo con <em>Permafrost<\/em>&#8230;<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/Om0jhPkOwhg&#038;hl=en&#038;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/Om0jhPkOwhg&#038;hl=en&#038;fs=1\" allowFullScreen=\"true\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00daltimamente el rock parece haber ingresado en una extra\u00f1a dimensi\u00f3n atemporal. La m\u00fasica actual y la m\u00fasica del pasado conviven, o compiten, en mayor igualdad de condiciones que antes de Internet: todo est\u00e1 disponible y, con perd\u00f3n, todo es gratis, as\u00ed que el chaval que se aficiona a Wolfmother puede regalarse tambi\u00e9n a Led Zeppelin [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1308,1849,2503,2529],"class_list":["post-580","post","type-post","status-publish","format-standard","hentry","category-musica","tag-howard-devoto","tag-magazine","tag-reuniones","tag-rock"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=580"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/580\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}