{"id":5768,"date":"2023-05-26T17:33:00","date_gmt":"2023-05-26T16:33:00","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5768"},"modified":"2023-05-26T17:33:00","modified_gmt":"2023-05-26T16:33:00","slug":"cancion-de-la-semana-sidiroun-parapetasma","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2023\/05\/26\/cancion-de-la-semana-sidiroun-parapetasma\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Sidiroun Parapetasma&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5769\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD-600x317.jpg\" alt=\"\" width=\"560\" height=\"296\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD-600x317.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD-300x158.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD-150x79.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD-768x405.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2023\/05\/MMMD.jpg 1200w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Qu\u00e9 bonitos son los reencuentros. Hace diez a\u00f1os, con la alegr\u00eda cascabelera que me caracteriza, dediqu\u00e9 el mes de julio a recomendar cuatro discos particularmente oscuros: aquella peque\u00f1a serie (que titul\u00e9 ejem, <a href=\"https:\/\/blogs.elcorreo.com\/evadidos\/2013\/07\/17\/verano-en-tinieblas-3-sacrificio\/\"><em>Verano en tinieblas<\/em><\/a>) tuvo como detonante mi encuentro casual con <em>Som Sakrifis<\/em>, un \u00e1lbum de los griegos Mohammad que me fascin\u00f3 con sus graves gimientes y reptantes. Mohammad eran un tr\u00edo con una formaci\u00f3n muy singular (contrabajo, chelo y osciladores) que se especializaba en drones profund\u00edsimos, de severidad casi lit\u00fargica. Aquel era un discazo capaz de transformar un chiringuito de playa en una ceremonia f\u00fanebre<\/p>\n<p>Y ah\u00ed les perd\u00ed la pista a Mohammad. No volv\u00ed a saber de ellos. Hasta hace unas cuantas semanas, cuando me enter\u00e9 por casualidad de que, desde hace mucho tiempo, se hacen llamar MMMD (o, si apostamos por la graf\u00eda griega, mucho m\u00e1s bonita, MMM\u0394). Ahora son un d\u00fao formado por los hermanos Veliotis y siguen a lo suyo, a lo que llaman <em>doom de c\u00e1mara<\/em>, aunque veo que en el tiempo que hemos pasado alejados han publicado tambi\u00e9n propuestas m\u00e1s r\u00edtmicas e incluso una apasionante colaboraci\u00f3n con un clavecinista barroco. Ahora acaban de editar un EP titulado <a href=\"https:\/\/mohammadsound.bandcamp.com\/album\/sidiroun-parapetasma\" rel=\"external nofollow\"><em>Sidiroun Parapetasma<\/em><\/a> que se abre con el tema hom\u00f3nimo, estos ocho minutos que son como ir hundi\u00e9ndose muy despacito en el pozo m\u00e1s negro.<\/p>\n<p>Y acabo con una curiosidad. Partiendo de esas coordenadas poco sandungueras, me ha sorprendido un poquit\u00edn ver que, cuando les piden una recomendaci\u00f3n musical en <a href=\"https:\/\/www.15questions.net\/interview\/fifteen-questions-interview-mmmd\/page-1\/\" rel=\"external nofollow\">esta entrevista<\/a>, los hermanos Veliotis eligen&#8230; \u00a1\u00a1\u00a1<em>Qui\u00e9n maneja mi barca<\/em>, de Remedios Amaya!!! Dicen as\u00ed: \u00abProbablemente, la mejor canci\u00f3n que se ha abierto camino hasta el festival de Eurovisi\u00f3n. La canci\u00f3n de Espa\u00f1a en 1983, que acab\u00f3 \u00faltima, con cero votos, es un hermoso ejemplo de pop, nueva ola y fusi\u00f3n flamenca con una l\u00ednea de bajo asesina\u00bb. Ol\u00e9 MMM\u0394, qu\u00e9 bien quedar\u00eda Remedios Amaya irrumpiendo en este v\u00eddeo a la vez playero e inquietante.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/VW_9I-lMK_U\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Qu\u00e9 bonitos son los reencuentros. Hace diez a\u00f1os, con la alegr\u00eda cascabelera que me caracteriza, dediqu\u00e9 el mes de julio a recomendar cuatro discos particularmente oscuros: aquella peque\u00f1a serie (que titul\u00e9 ejem, Verano en tinieblas) tuvo como detonante mi encuentro casual con Som Sakrifis, un \u00e1lbum de los griegos Mohammad que me fascin\u00f3 con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,804,1193,3983,2024],"class_list":["post-5768","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-doom","tag-grecia","tag-mmmd","tag-mohammad"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5768"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5768\/revisions"}],"predecessor-version":[{"id":5770,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5768\/revisions\/5770"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}