{"id":576,"date":"2008-09-03T18:39:00","date_gmt":"2008-09-03T18:39:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=576"},"modified":"2008-09-03T18:39:00","modified_gmt":"2008-09-03T18:39:00","slug":"frescura-francesa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/09\/03\/frescura-francesa\/","title":{"rendered":"Frescura francesa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Plastiscines\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"532\" height=\"647\" \/><br \/>\n<a href=\"http:\/\/www.myspace.com\/plastiscine\" target=\"_blank\" rel=\"external nofollow\">Plastiscines<\/a>. Para qu\u00e9 voy a decir m\u00e1s, si s\u00e9 que, una vez vista la foto, muchos lectores s\u00f3lo necesitan saber el nombre del grupo para hacerse fans devotos. Pero bueno, a lo mejor con una sola palabra el <em>post <\/em>quedar\u00eda demasiado corto, as\u00ed que les contar\u00e9 que son francesas, que proceden de familias bastante pijas \u2013digamos, para no parecer tan primarios, que sus padres pertenecen a la burgues\u00eda bohemia\u2013 y que est\u00e1n encuadradas en una oleada de grupos galos bautizados creativamente como los <em>beb\u00e9s rockeros<\/em>. Su primer \u00e1lbum, <em>LP1<\/em>, es del a\u00f1o pasado, pero yo lo he descubierto con retraso y no me voy a privar de recomendarlo, por m\u00e1s que el mundo entero compita en escuchar discos que todav\u00eda no se han editado.<\/p>\n<p>La m\u00fasica de las Plastiscines se mueve entre el garaje ligero y los Strokes \u2013otros pijaz&#8230; burgueses bohemios, quiero decir\u2013, pero ellas interpretan sus canciones con lo que podr\u00edamos llamar frescura francesa. Al fin y al cabo, son jovenc\u00edsimas y se han criado escuchando \u201cun mont\u00f3n de R&#038;B y rap\u201d, dicho sea lo de R&#038;B en sentido moderno, as\u00ed que no ten\u00edan ni idea de rock hasta que se quedaron fascinadas con los Strokes y los Libertines. \u00bfUn bluff? <em>On verra<\/em>, que dir\u00eda Otegi, pero seguro que a muchos de ustedes tambi\u00e9n les gustan canciones como \u00e9sta:<\/p>\n<p><object style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/iNzztEHt-eA&#038;hl=es&#038;fs=1\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed style=\"border: 0pt none; margin: 0pt; background: none repeat scroll 0% 0% transparent; -moz-background-inline-policy: -moz-initial;\" width=\"425\" height=\"344\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/iNzztEHt-eA&#038;hl=es&#038;fs=1\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Plastiscines. Para qu\u00e9 voy a decir m\u00e1s, si s\u00e9 que, una vez vista la foto, muchos lectores s\u00f3lo necesitan saber el nombre del grupo para hacerse fans devotos. Pero bueno, a lo mejor con una sola palabra el post quedar\u00eda demasiado corto, as\u00ed que les contar\u00e9 que son francesas, que proceden de familias bastante pijas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,1066,2358,2529],"class_list":["post-576","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-francia","tag-plastiscines","tag-rock"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}