{"id":5562,"date":"2022-09-16T16:30:00","date_gmt":"2022-09-16T15:30:00","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5562"},"modified":"2022-09-16T16:30:00","modified_gmt":"2022-09-16T15:30:00","slug":"cancion-de-la-semana-the-frozen-ground","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2022\/09\/16\/cancion-de-la-semana-the-frozen-ground\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;The Frozen Ground&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-5563\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/09\/plague-pits.jpg\" alt=\"\" width=\"316\" height=\"316\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/09\/plague-pits.jpg 595w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/09\/plague-pits-150x150.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/09\/plague-pits-300x300.jpg 300w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/>Uno puede visitar siempre <a href=\"https:\/\/thisisplaguepits.bandcamp.com\/\" rel=\"external nofollow\">el perfil en Bandcamp<\/a> de <a href=\"https:\/\/www.facebook.com\/thisisplaguepits\/\" rel=\"external nofollow\">Plague Pits<\/a> con la ilusi\u00f3n de encontrarse algo nuevo, porque este grupo suizo (cuarteto, colectivo o lo que buenamente sea) va lanzando EPs y recopilaciones de EPs en animada cadencia: caramba, de junio aqu\u00ed han aparecido tres referencias y, de hecho, esta canci\u00f3n que les traigo pertenece ya a la antepen\u00faltima, as\u00ed que se va quedando viejita aunque solo tenga tres meses. Esta manera de operar encaja muy bien con el perfil esquivo de la banda de Berna, un enigm\u00e1tico proyecto en blanco y negro que habr\u00eda podido aparecer perfectamente en aquellos cat\u00e1logos que el sello Mute encartaba en sus elep\u00e9s (ay, aquellos papelotes, c\u00f3mo me hac\u00edan so\u00f1ar con ruidos desconocidos y estimulantes) o incluso en alg\u00fan fanzine fotocopiado de los ochenta m\u00e1s industrialoides. Hasta el nombre (que entiendo que se refiere a las fosas comunes para los muertos por la peste) encaja en aquellos contextos, y no digamos la actitud: Plague Pits aspiran a poner m\u00fasica al fracaso de nuestra especie y la progresiva y sistem\u00e1tica destrucci\u00f3n de nuestro mundo. \u00abOnda fr\u00eda para un planeta que se calienta\u00bb, dicen ellos. O <em>Ruinas pintorescas de un futuro pr\u00f3ximo<\/em>, como apunta uno de sus t\u00edtulos.<\/p>\n<p>Confesar\u00e9 aqu\u00ed que muchos proyectos del rollo <em>minimal synth<\/em> tienden a aburrirme, por esa costumbre de tirar siempre de la receta m\u00e1s previsible, pero por alguna raz\u00f3n eso no me ocurre con esta gente extra\u00f1a. A veces se aventuran por sonidos algo m\u00e1s \u00e1speros, pero en general lo suyo es un pop fr\u00edo, distanciado, elegante y pesimista, que va m\u00e1s all\u00e1 de las referencias post-punk y a menudo remite directamente a Kraftwerk (no hay m\u00e1s que ver la portada de <em>Transnecropolitan<\/em>, el minielep\u00e9 donde aparece <em>The Frozen Ground<\/em>) e incluso, como indica alguna cr\u00edtica por ah\u00ed, pueden evocar ocasionalmente los paisajes electr\u00f3nicos de Jean-Michel Jarre (que a algunos les espantar\u00e1, pero fue una de mis primeras pasiones musicales). Si les gusta, <a href=\"https:\/\/thisisplaguepits.bandcamp.com\/album\/a-gift-for-disaster\" rel=\"external nofollow\">aqu\u00ed<\/a> pueden descargarse por la cara, o por el precio que quieran pagar, una bonita recopilaci\u00f3n de sus tres primeros ep\u00e9s. O tambi\u00e9n compr\u00e1rsela en versi\u00f3n casete, que seguramente es lo m\u00e1s indicado en su caso.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=1670838000\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=101460666\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/thisisplaguepits.bandcamp.com\/album\/transnecropolitan\" rel=\"external nofollow\">Transnecropolitan by Plague Pits<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Uno puede visitar siempre el perfil en Bandcamp de Plague Pits con la ilusi\u00f3n de encontrarse algo nuevo, porque este grupo suizo (cuarteto, colectivo o lo que buenamente sea) va lanzando EPs y recopilaciones de EPs en animada cadencia: caramba, de junio aqu\u00ed han aparecido tres referencias y, de hecho, esta canci\u00f3n que les traigo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,883,3927,2785],"class_list":["post-5562","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-electronica","tag-plague-pits","tag-suiza"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5562"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5562\/revisions"}],"predecessor-version":[{"id":5564,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5562\/revisions\/5564"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}