{"id":554,"date":"2008-05-16T18:28:00","date_gmt":"2008-05-16T18:28:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=554"},"modified":"2008-05-16T18:28:00","modified_gmt":"2008-05-16T18:28:00","slug":"dura-durango","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/05\/16\/dura-durango\/","title":{"rendered":"Dura Durango"},"content":{"rendered":"<div class=\"p\">\n<div class=\"p\">Pocos grupos transmiten tanta sensaci\u00f3n de dureza como <a id=\"link_0\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2007\/9\/11\/escoria-luxe\" href=\"..\/evadidos\/2007\/9\/11\/escoria-luxe\">Napalm Death<\/a>. Es cierto que la dureza admite muchas formulaciones y se puede vincular a variables como el ruido, la velocidad o simplemente la capacidad de desquiciar al oyente, pero la banda brit\u00e1nica cotiza alto en cualquiera de estas clasificaciones. De hecho, en sus comienzos all\u00e1 por los 80, estos cerriles mocetones se vieron obligados a inventarse un g\u00e9nero para definir esa suma de factores, ya que no estaban dispuestos a ceder un \u00e1pice en sus aspiraciones maximalistas: a grandes trazos, tomaron el estruendo del metal, la velocidad del hardcore y la vocaci\u00f3n irritante de la electr\u00f3nica m\u00e1s radical y llamaron <em>grindcore <\/em>al monstruoso resultado. La <a id=\"link_1\" title=\"http:\/\/en.wikipedia.org\/wiki\/Napalm_Death\" href=\"http:\/\/en.wikipedia.org\/wiki\/Napalm_Death\" rel=\"external nofollow\">Wikipedia<\/a> resulta muy ilustrativa a la hora de analizar sus influencias de partida, ya que entre ellas no hay mucho heavy que se diga: aparecen anarcopunks como Crass o The Ex, pioneros de lo industrial como Throbbing Gristle (v\u00e9ase el <em>post <\/em>precedente) y bestias inclasificables como los Swans y su rock machac\u00f3n y ag\u00f3nico.Es verdad que de aquellos fundadores del grupo no queda nadie \u2013el m\u00e1s veterano es el corpulento bajista Shane Embury, enrolado en 1987\u2013, que ahora hay miles de indistinguibles escuadrones <span id=\"U802267986799HJH\" class=\"span\" style=\"font-style: italic;\">grincoretas <\/span>y que Napalm Death dieron la espalda hace mucho a su sonido primigenio y a los excesos absurdos que conllevaba, como esas <a id=\"link_2\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2007\/5\/17\/visto-y-visto\" href=\"..\/evadidos\/2007\/5\/17\/visto-y-visto\">canciones de segundo y pico<\/a>. Pero sus conciertos, como el de esta noche en Durango junto a Suffocation y Warbringer, siguen siendo una experiencia memorable, abrumadora y muy satisfactoria, siempre que no te absorba el habitual v\u00f3rtice enloquecido y violento de las primeras filas: a veces, conviene admitir que uno es un poquito blando.<\/p>\n<\/div>\n<\/div>\n<p><object width=\"425\" height=\"355\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/lOb4knQ8Yks&#038;hl=en\" \/><embed width=\"425\" height=\"355\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/lOb4knQ8Yks&#038;hl=en\" wmode=\"transparent\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pocos grupos transmiten tanta sensaci\u00f3n de dureza como Napalm Death. Es cierto que la dureza admite muchas formulaciones y se puede vincular a variables como el ruido, la velocidad o simplemente la capacidad de desquiciar al oyente, pero la banda brit\u00e1nica cotiza alto en cualquiera de estas clasificaciones. De hecho, en sus comienzos all\u00e1 por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[602,825,1200,1955,2111],"class_list":["post-554","post","type-post","status-publish","format-standard","hentry","category-musica","tag-conciertos","tag-durango","tag-grindcore","tag-metal","tag-napalm-death"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=554"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/554\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}