{"id":5478,"date":"2022-05-13T10:33:17","date_gmt":"2022-05-13T09:33:17","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5478"},"modified":"2022-05-13T10:33:17","modified_gmt":"2022-05-13T09:33:17","slug":"cancion-de-la-semana-digging","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2022\/05\/13\/cancion-de-la-semana-digging\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Digging&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-5479\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads-600x751.jpg\" alt=\"\" width=\"360\" height=\"451\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads-600x751.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads-120x150.jpg 120w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads-240x300.jpg 240w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads-768x961.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2022\/05\/Nothingheads.jpg 853w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/>M\u00e1s all\u00e1 del dato fundamental de que uno de sus miembros luce un hermoso bigote, poco puedo contar de los londinenses <a href=\"https:\/\/linktr.ee\/Nothingheads\" rel=\"external nofollow\">Nothingheads<\/a>, firmantes de nuestra canci\u00f3n de esta semana. Por ah\u00ed los definen como post-punk, pero esa etiqueta se ha vuelto tan el\u00e1stica que, a este paso, va a acabar equivaliendo a <em>rock con guitarras<\/em>: yo he de confesar que, cuando escuch\u00e9 <em>Digging<\/em>, ni siquiera se me pas\u00f3 en ning\u00fan momento por la cabeza la expresi\u00f3n <em>post-punk<\/em>, pero tambi\u00e9n es verdad que no deb\u00eda de andar muy fino, porque tampoco se me pas\u00f3 por la cabeza la palabra <em>Londres<\/em> y me qued\u00e9 convencido de haber o\u00eddo a un grupo americano. Estadounidense, quiero decir, porque lo suyo me hab\u00eda sonado m\u00e1s a herencia del rock alternativo de aquel pa\u00eds que a revisi\u00f3n de las exploraciones brit\u00e1nicas de la oscuridad post-punk.<\/p>\n<p>Nothingheads son un cuarteto relativamente nuevo que solo ha editado un pu\u00f1ado de sencillos. En <a href=\"https:\/\/nothingheads.bandcamp.com\/album\/digging\" rel=\"external nofollow\">este que acaba de salir<\/a> se ponen especialmente intensos y ruidosos, con cinco minutos y medio de fibra guitarrera, voces majaras de rock and roll mutante y un pasaje final muy de sacudir cabezas y cabellos. Ah, una cosa s\u00ed puedo contar de esta gente: parece que les gusta inspirarse en asuntos poco comunes en este mundito nuestro del rock. Una de sus primeras canciones, <em>Topsy<\/em>, estaba dedicada a <a href=\"https:\/\/en.wikipedia.org\/wiki\/Topsy_(elephant)\" rel=\"external nofollow\">la elefanta de ese nombre<\/a> que fue electrocutada en Coney Island en 1903 (y que, caramba, por alguna raz\u00f3n no inclu\u00ed en <a href=\"https:\/\/www.elcorreo.com\/vivir\/artes\/vidas-extranas-muertes-20200614173354-ntrc.html\" rel=\"external nofollow\">mi reportajito<\/a> sobre vidas y muertes de elefantes de circo), mientras que Digging tiene su punto de partida en las fotos de minas amaz\u00f3nicas que Sebasti\u00e3o Salgado tom\u00f3 en los 80.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=2330236719\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=3712827227\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/nothingheads.bandcamp.com\/album\/digging\" rel=\"external nofollow\">Digging by Nothingheads<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>M\u00e1s all\u00e1 del dato fundamental de que uno de sus miembros luce un hermoso bigote, poco puedo contar de los londinenses Nothingheads, firmantes de nuestra canci\u00f3n de esta semana. Por ah\u00ed los definen como post-punk, pero esa etiqueta se ha vuelto tan el\u00e1stica que, a este paso, va a acabar equivaliendo a rock con guitarras: [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[461,1766,3908],"class_list":["post-5478","post","type-post","status-publish","format-standard","hentry","category-musica","tag-cancion-de-la-semana","tag-londres","tag-nothingheads"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5478"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5478\/revisions"}],"predecessor-version":[{"id":5480,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5478\/revisions\/5480"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}