{"id":547,"date":"2008-04-13T19:48:00","date_gmt":"2008-04-13T19:48:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=547"},"modified":"2008-04-13T19:48:00","modified_gmt":"2008-04-13T19:48:00","slug":"sesion-dominical-3","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/04\/13\/sesion-dominical-3\/","title":{"rendered":"Sesi\u00f3n dominical 3"},"content":{"rendered":"<p>Como dice un amigo m\u00edo, hasta esta semana \u00e9ramos mayores que los futbolistas, pero ahora empezamos a ser tambi\u00e9n mayores que los ministros. Y quiz\u00e1 sea por el sentido de la responsabilidad propio de esta edad avanzada, pero el caso es que me siento inesperadamente capaz de cumplir por tercera semana una obligaci\u00f3n autoimpuesta, como un hombrecito: en la sesi\u00f3n de este domingo les va el impetuoso garaje de <strong>White Denim<\/strong>, el blues-jazz nocturno de <strong>Melody Gardot<\/strong> (en la foto de abajo), el indie pop sensible de <strong>Bitter Bitter Weeks<\/strong>, la chispeante energ\u00eda adolescente de <strong>Be Your Own Pet<\/strong> y la <em>macarrizaci\u00f3n <\/em>que hacen <strong>Ministry<\/strong> de la vieja canci\u00f3n de trabajo<em> <\/em><a id=\"link_1\" title=\"http:\/\/en.wikipedia.org\/wiki\/Black_Betty\" href=\"http:\/\/en.wikipedia.org\/wiki\/Black_Betty\" rel=\"external nofollow\">Black Betty<\/a> (muy similar, y para mi gusto inferior, a la que firmaron hace cuatro a\u00f1os los australianos Spiderbait). Todo <em>made in USA<\/em>, ha salido as\u00ed.<\/p>\n<p><a id=\"link_2\" title=\"http:\/\/evadidos3.muxtape.com\/\" href=\"http:\/\/evadidos3.muxtape.com\/\" rel=\"external nofollow\"> Est\u00e1 aqu\u00ed.<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Melody Gardot\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"600\" height=\"338\" \/><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Como dice un amigo m\u00edo, hasta esta semana \u00e9ramos mayores que los futbolistas, pero ahora empezamos a ser tambi\u00e9n mayores que los ministros. Y quiz\u00e1 sea por el sentido de la responsabilidad propio de esta edad avanzada, pero el caso es que me siento inesperadamente capaz de cumplir por tercera semana una obligaci\u00f3n autoimpuesta, como [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[285,1943,2004,2363,2529,2641,3217],"class_list":["post-547","post","type-post","status-publish","format-standard","hentry","category-musica","tag-be-your-own-pet","tag-melody-gardot","tag-ministry","tag-playlist","tag-rock","tag-sesion-dominical","tag-white-denim"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=547"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/547\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}