{"id":545,"date":"2008-04-08T21:20:00","date_gmt":"2008-04-08T21:20:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=545"},"modified":"2008-04-08T21:20:00","modified_gmt":"2008-04-08T21:20:00","slug":"doherty-entre-rejas","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/04\/08\/doherty-entre-rejas\/","title":{"rendered":"Doherty, entre rejas"},"content":{"rendered":"<p>Al pobre Pete Doherty <a id=\"link_0\" title=\"http:\/\/news.bbc.co.uk\/2\/hi\/entertainment\/7337212.stm\" href=\"http:\/\/news.bbc.co.uk\/2\/hi\/entertainment\/7337212.stm\" rel=\"external nofollow\">lo han enchironado<\/a> por incumplir las especificaciones de su libertad condicional: aparte de que su sentencia por posesi\u00f3n de drogas y conducci\u00f3n ilegal le exig\u00eda someterse a rehabilitaci\u00f3n, y no s\u00e9 yo si el concepto de <em>rehabilitado <\/em>se ha vuelto tan el\u00e1stico como para incluir a este hombre, la cuesti\u00f3n es que no acudi\u00f3 a una de sus citas en el juzgado y lleg\u00f3 tarde a otra. Cosa l\u00f3gica, por otra parte: no tengo ninguna duda de que Pete estar\u00e1 adornado de muchas virtudes, pero jam\u00e1s imagin\u00e9 que entre ellas pudiese estar la puntualidad. Si se inventase la m\u00e1quina de visitar cerebros, yo me apresurar\u00eda a hacer una excursi\u00f3n al de este tipo, porque sus mecanismos mentales han de ser un espect\u00e1culo fascinante, sobrecogedor, digno de quedarse con la boca abierta. Como suele estar \u00e9l, por otra parte, y lo digo desde mi <a id=\"link_1\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2006\/3\/3\/pro-doherty\" href=\"..\/evadidos\/2006\/3\/3\/pro-doherty\">cari\u00f1osa postura pro-Doherty<\/a>.<\/p>\n<p>En realidad, en el actual mundo de la m\u00fasica, mercantilista y sostenido por la ambici\u00f3n, Doherty es excepcional porque no rige su vida por c\u00e1lculos. Lo de hoy sirve de prueba: por ahorrarse echar una firma en el juzgado, una tarea que es s\u00f3lo un poco m\u00e1s trabajosa que bajar a por el pan, va a tener que posponer el conciertazo que ten\u00eda programado este mes en el Royal Albert Hall. Y, si le obligan a cumplir las 14 semanas de condena, tampoco podr\u00e1 estar con los Babyshambles en el festival de Glastonbury. Ay, este hombre es uno de los pocos idealistas que quedan en el rock de hoy, aunque no tenga muy claro qu\u00e9 ideas son las suyas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgcen\" title=\"Pete Doherty\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\" alt=\"\" width=\"550\" height=\"366\" \/><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al pobre Pete Doherty lo han enchironado por incumplir las especificaciones de su libertad condicional: aparte de que su sentencia por posesi\u00f3n de drogas y conducci\u00f3n ilegal le exig\u00eda someterse a rehabilitaci\u00f3n, y no s\u00e9 yo si el concepto de rehabilitado se ha vuelto tan el\u00e1stico como para incluir a este hombre, la cuesti\u00f3n es [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[248,814,1546,2319],"class_list":["post-545","post","type-post","status-publish","format-standard","hentry","category-musica","tag-babyshambles","tag-drogas","tag-justicia","tag-pete-doherty"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}