{"id":541,"date":"2008-04-03T16:58:00","date_gmt":"2008-04-03T16:58:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=541"},"modified":"2008-04-03T16:58:00","modified_gmt":"2008-04-03T16:58:00","slug":"la-cuenta-atras-final","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/04\/03\/la-cuenta-atras-final\/","title":{"rendered":"La cuenta atr\u00e1s final"},"content":{"rendered":"<p>Y hoy toca Kobetasonik, porque esta org\u00eda de festivales no nos deja descansar. Los organizadores han cerrado ya el cartel del viernes 20 de junio y est\u00e1n a falta de dos grupos para completar el del s\u00e1bado 21. Las \u00faltimas incorporaciones son Slayer, <a id=\"link_2\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2006\/4\/5\/ministerio-del-ruido\" href=\"..\/evadidos\/2006\/4\/5\/ministerio-del-ruido\">Ministry<\/a>, <a id=\"link_1\" title=\"http:\/\/blogs.elcorreodigital.com\/evadidos\/2007\/1\/19\/europeismo-tope\" href=\"..\/evadidos\/2007\/1\/19\/europeismo-tope\">Europe<\/a>, Dio, Sonata Arctica, Obituary, Tigertailz, Su Ta Gar y Black Tide. Como tendr\u00e1n ya la cabeza como un bombo, igual que si Ministry y Slayer tocasen una jam session dentro de su cr\u00e1neo, les ordenar\u00e9 la cosa por jornadas:<\/p>\n<p><strong> Viernes 20: <\/strong>Judas Priest, Slayer, Helloween, Ministry, Gamma Ray, Apocalyptica, Sonata Arctica, Cavalera Conspiracy, Gotthard, Airbourne, Su Ta Gar y Black Tide.<br \/>\n<strong>S\u00e1bado 21:<\/strong> Kiss, Europe, Blind Guardian, Dio, Saxon, Tesla, Obituary, Death Angel, Tigertailz y dos bandas m\u00e1s que se confirmar\u00e1n el mes que viene.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"img_0\" class=\"imgdcha\" style=\"width: 352px; height: 266px;\" title=\"Tigertailz\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/Tailz2.JPG\" alt=\"\" width=\"298\" height=\"226\" \/>A m\u00ed no me busquen por Kobetas, que estar\u00e9 esos d\u00edas tomando el sol e infl\u00e1ndome de vino blanco en la Costa Brava. Pero, si no hubiesen programado mal\u00e9volamente el festival para coincidir con mis vacaciones de verano, no faltar\u00eda a la primera jornada: ver casi seguidos a Ministry, Slayer y Judas merece clar\u00edsimamente la pena, con un descanso durante la <em>helloweenada <\/em>para pastar y abrevar. El programa del s\u00e1bado me atrae menos, pero seguro que el compa\u00f1ero Arrieta est\u00e1 emocionado ante la gloriosa venida de sus h\u00e9roes de adolescencia Tigertailz (en la foto). Hagamos un test: \u00bfa qui\u00e9n tienen m\u00e1s ganas de ver de los que hay, qu\u00e9 grupo a\u00f1adir\u00edan y a cu\u00e1l tachar\u00edan sin ning\u00fan remordimiento? Yo me respondo Judas, <a id=\"link_0\" title=\"http:\/\/www.inquisition666.tk\/\" href=\"http:\/\/www.inquisition666.tk\/\" rel=\"external nofollow\">Inquisition<\/a> (je, je) y Helloween.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Y hoy toca Kobetasonik, porque esta org\u00eda de festivales no nos deja descansar. Los organizadores han cerrado ya el cartel del viernes 20 de junio y est\u00e1n a falta de dos grupos para completar el del s\u00e1bado 21. Las \u00faltimas incorporaciones son Slayer, Ministry, Europe, Dio, Sonata Arctica, Obituary, Tigertailz, Su Ta Gar y Black [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[327,1018,1608,2004,2529,2694],"class_list":["post-541","post","type-post","status-publish","format-standard","hentry","category-musica","tag-bilbao","tag-festivales","tag-kobetasonik","tag-ministry","tag-rock","tag-slayer"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/541\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}