{"id":532,"date":"2008-03-04T18:21:00","date_gmt":"2008-03-04T18:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=532"},"modified":"2008-03-04T18:21:00","modified_gmt":"2008-03-04T18:21:00","slug":"chikilicuatre-milkyway-y-terasbetoni","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/03\/04\/chikilicuatre-milkyway-y-terasbetoni\/","title":{"rendered":"Chikilicuatre, Milkyway y Ter\u00e4sbetoni"},"content":{"rendered":"<p>Quiz\u00e1 lo de Chikilicuatre sea de mucha risa, no dir\u00e9 que no, pero a m\u00ed me da bastante rabia. Aunque hablemos de algo tan intrascendente y viciado como el festival de <a id=\"link_2\" title=\"http:\/\/www.myspace.com\/eurovision2008\" href=\"http:\/\/www.myspace.com\/eurovision2008\" rel=\"external nofollow\">Eurovisi\u00f3n<\/a>, me fastidia que los programas de humor conviertan cualquier convocatoria en excusa para un chiste y aborten, con su poder de movilizaci\u00f3n, toda posibilidad de seriedad o, lo que es m\u00e1s importante, de gracia espont\u00e1nea. Que s\u00ed, que yo tambi\u00e9n me r\u00edo y hago el robocop, pero me habr\u00eda dejado mucho mejor cuerpo que La Casa Azul quedaran los primeros en la votaci\u00f3n: habr\u00eda sido un est\u00edmulo para confiar en la humanidad y no una prueba m\u00e1s de que la humanidad es f\u00e1cilmente manipulable, tan d\u00f3cil que s\u00f3lo se pone traviesa cuando se lo mandan desde una pantalla.<\/p>\n<p>Dicho esto, unos se\u00f1ores tan serios como los austriacos enviaron al c\u00f3mico <a id=\"link_1\" title=\"http:\/\/www.alfpoier.at\/\" href=\"http:\/\/www.alfpoier.at\/\" rel=\"external nofollow\">Alf Poier<\/a> en 2003 y obtuvieron un merecido sexto puesto, as\u00ed que no deber\u00edamos desconfiar de las posibilidades de Chikilicuatre en caso de salir escogido (el representante irland\u00e9s, <a id=\"link_0\" title=\"http:\/\/www.youtube.com\/watch?v=ZXRi6FiC96E\" href=\"http:\/\/www.youtube.com\/watch?v=ZXRi6FiC96E\" rel=\"external nofollow\">Dustin el Pavo<\/a>, compite en la misma liga). Pero yo me quedo con La Casa Azul, desde luego: su \u00faltimo disco me parece un hito del pop espa\u00f1ol sin m\u00e1s calificativos, que lo mismo puede gustar a los indies que a un se\u00f1or mayor aficionado a la ELO, y la \u00fanica duda es c\u00f3mo adaptar\u00e1n al directo ese lujo de producci\u00f3n y c\u00f3mo ser\u00e1 capaz de hacerlo Guille Milkyway: \u201cEst\u00e1 claro que no soy ning\u00fan portento cantando y que tiendo a olvidarme las letras y muchas veces hasta las melod\u00edas. Pero creo que, en esta ocasi\u00f3n, la gente que ha votado a La Casa Azul ha votado por algo muy distinto a eso\u201d, escribe en <a id=\"link_0\" title=\"http:\/\/www.myspace.com\/lacasaazulband\" href=\"http:\/\/www.myspace.com\/lacasaazulband\" rel=\"external nofollow\">su Myspace<\/a>. Eso s\u00ed, como s\u00e9 que muchos de ustedes quieren hacerse hijos adoptivos de Finlandia, les dejo con la canci\u00f3n que manda este a\u00f1o el pa\u00eds de las saunas y el metal: <em>Miss\u00e4 Miehet Ratsastaa<\/em>, del grupo Ter\u00e4sbetoni.<\/p>\n<p><strong>Actualizado al final de la gala: <\/strong>pues nada, mandamos a Chikilicuatre. Y me alegro, porque por un momento he temido que iba a ganar Coral, y eso s\u00ed que me espantaba. Creo que a Uribarri no le ha hecho mucha gracia la decisi\u00f3n popular, porque negaba con el dedo, como reprendiendo a la audiencia por su poco criterio. Por cierto, \u00bfqu\u00e9 pasar\u00eda si Chikilicuatre, en vez de concursar en la gala de esta noche, se presentase a las elecciones de dentro de unas horas?<\/p>\n<p><object width=\"425\" height=\"355\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/dgOxYaNMIeU\" \/><embed width=\"425\" height=\"355\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/dgOxYaNMIeU\" wmode=\"transparent\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1 lo de Chikilicuatre sea de mucha risa, no dir\u00e9 que no, pero a m\u00ed me da bastante rabia. Aunque hablemos de algo tan intrascendente y viciado como el festival de Eurovisi\u00f3n, me fastidia que los programas de humor conviertan cualquier convocatoria en excusa para un chiste y aborten, con su poder de movilizaci\u00f3n, toda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[534,966,1086,1637,2848],"class_list":["post-532","post","type-post","status-publish","format-standard","hentry","category-musica","tag-chikilicuatre","tag-eurovision","tag-frikismo","tag-la-casa-azul","tag-television"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=532"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/532\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}