{"id":5283,"date":"2021-09-03T12:58:41","date_gmt":"2021-09-03T11:58:41","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5283"},"modified":"2021-09-03T12:58:41","modified_gmt":"2021-09-03T11:58:41","slug":"cancion-de-la-semana-phonecalls-on-my-deathbed","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2021\/09\/03\/cancion-de-la-semana-phonecalls-on-my-deathbed\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Phonecalls On My Deathbed&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-5284\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/09\/Lassie-600x478.jpg\" alt=\"\" width=\"394\" height=\"314\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/09\/Lassie-600x478.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/09\/Lassie-150x119.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/09\/Lassie-300x239.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/09\/Lassie.jpg 637w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/>No conoc\u00eda de nada a Lassie, una banda de Leipzig que lleva tres a\u00f1os lanzando material, y en estas vacaciones de agosto me ha deslumbrado <a href=\"https:\/\/discosperoquebien.bandcamp.com\/album\/the-golden-age-of\" rel=\"external nofollow\">la casete<\/a> que les ha editado el sello valenciano <a href=\"https:\/\/www.facebook.com\/profile.php?id=100032106084578\" rel=\"external nofollow\">Discos Peroqu\u00e9bien<\/a>. Es un fascinante artefacto (disponible en <em>streaming<\/em> para los que ya ni siquiera tenemos pletina) que recopila todas sus grabaciones hasta el momento, una andanada de quince canciones que acaban formando un \u00e1lbum tan an\u00f3malo como perfecto. La propia discogr\u00e1fica (\u00bfcasetogr\u00e1fica?) describe al quinteto alem\u00e1n como \u00abruidosos y divertidos a partes iguales\u00bb, y es un perfil certero, porque Lassie cultivan una general desfachatez en la actitud y el sonido, como si fuesen un grupo de psic\u00f3ticos que pasaron su infancia escuchando a Devo, The Fall y otros insignes extraviados. Qu\u00e9 gusto da cuando la falta de respeto por lo convencional se al\u00eda con las ganas de pasarlo bien.<\/p>\n<p>Cualquiera de los cortes valdr\u00eda para estar aqu\u00ed, pero voy a tirar por el primero del lote, que es tambi\u00e9n uno de los m\u00e1s largos, o sea, de los pocos que superan los tres minutos. Veo en su Bandcamp que pertenece a su primera referencia, de comienzos de 2018, y es un himno de post-punk kamikaze y majara. \u00abSigo recibiendo llamadas de tel\u00e9fono en mi lecho de muerte\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=2867526671\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=3606537484\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/discosperoquebien.bandcamp.com\/album\/the-golden-age-of\" rel=\"external nofollow\">The Golden Age Of&#8230; by Lassie<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No conoc\u00eda de nada a Lassie, una banda de Leipzig que lleva tres a\u00f1os lanzando material, y en estas vacaciones de agosto me ha deslumbrado la casete que les ha editado el sello valenciano Discos Peroqu\u00e9bien. Es un fascinante artefacto (disponible en streaming para los que ya ni siquiera tenemos pletina) que recopila todas sus [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[99,461,490,3869],"class_list":["post-5283","post","type-post","status-publish","format-standard","hentry","category-musica","tag-alemania","tag-cancion-de-la-semana","tag-casetes","tag-lassie"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5283"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5283\/revisions"}],"predecessor-version":[{"id":5285,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5283\/revisions\/5285"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}