{"id":5262,"date":"2021-07-03T09:56:39","date_gmt":"2021-07-03T08:56:39","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=5262"},"modified":"2021-07-03T09:56:39","modified_gmt":"2021-07-03T08:56:39","slug":"cancion-de-la-semana-apache","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2021\/07\/03\/cancion-de-la-semana-apache\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Apache&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5263\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/07\/Rien-Virgule-600x339.jpg\" alt=\"\" width=\"559\" height=\"316\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/07\/Rien-Virgule-600x339.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/07\/Rien-Virgule-150x85.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/07\/Rien-Virgule-300x170.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2021\/07\/Rien-Virgule.jpg 695w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Al leer sobre <a href=\"https:\/\/rienvirgule.jimdofree.com\/\" rel=\"external nofollow\">Rien Virgule<\/a>, uno se imagina su m\u00fasica mucho m\u00e1s inc\u00f3moda e impenetrable de lo que realmente es. Suele suceder con ciertos estilos que no se ajustan a esas etiquetas de las que todos abominamos pero que luego todos empleamos: a falta de una categor\u00eda evidente, la descripci\u00f3n tira de t\u00e9rminos como improvisaci\u00f3n, experimentaci\u00f3n y electroac\u00fastica y el lector empieza a escuchar en su mente un antip\u00e1tico engrudo con pretensiones. Pero qu\u00e9 va: este <em>Apache<\/em>, tema de adelanto de lo que ser\u00e1 su tercer \u00e1lbum, arranca con tres minutos esencialmente ruidistas, pero a partir de ah\u00ed se acomoda a estructuras tambi\u00e9n libres pero m\u00e1s amables, de lo que podr\u00edamos llamar pop electr\u00f3nico entre lo ambiental y lo ceremonial. El tr\u00edo bordel\u00e9s se toma la cosa sin prisas, renunciando a esa exigencia arbitraria de que las canciones tengan que durar tres o cuatro minutos, y se concede nada menos que doce minutos para desarrollar una canci\u00f3n de paso glacial y atm\u00f3sfera misteriosa. S\u00ed, s\u00ed, lo s\u00e9, estoy cayendo en el mismo error de la descripci\u00f3n herm\u00e9tica, as\u00ed que mejor le dan al play.<\/p>\n<p>Este tercer \u00e1lbum de Rien Virgule (con el bonito t\u00edtulo de <a href=\"https:\/\/lesdisquesdupermafrost.bandcamp.com\/album\/la-consolation-des-violettes\" rel=\"external nofollow\"><em>La consolation des violettes<\/em><\/a>) llega como una sorpresa, porque muchos hab\u00edan dado por terminada su carrera hace un par de a\u00f1os, cuando falleci\u00f3 uno de los miembros del grupo, hasta entonces cuarteto. Los tres supervivientes (la artista pl\u00e1stica y fabricante de m\u00e1scaras Anne Careil a la voz y los sintes, Manuel Duval a los \u00absintetizadores horizontales\u00bb y Mathias Pontevia a la \u00abbater\u00eda horizontal\u00bb) fueron los primeros en asombrarse al descubrir que entre ellos circulaba \u00abla misma savia incandescente\u00bb cuando volvieron a tocar juntos y que Jean-Marc, el compa\u00f1ero muerto, les hab\u00eda legado de alguna manera \u00absu parte del caos\u00bb. El resultado es este \u00abrevoltijo de metal, vidrios rotos y chispas de vida\u00bb, de absorbente melancol\u00eda industrial.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=644284735\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=1463324802\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/lesdisquesdupermafrost.bandcamp.com\/album\/la-consolation-des-violettes\" rel=\"external nofollow\">La Consolation Des Violettes by Rien Virgule<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Al leer sobre Rien Virgule, uno se imagina su m\u00fasica mucho m\u00e1s inc\u00f3moda e impenetrable de lo que realmente es. Suele suceder con ciertos estilos que no se ajustan a esas etiquetas de las que todos abominamos pero que luego todos empleamos: a falta de una categor\u00eda evidente, la descripci\u00f3n tira de t\u00e9rminos como [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3863,461,883,1066,3864],"class_list":["post-5262","post","type-post","status-publish","format-standard","hentry","category-musica","tag-burdeos","tag-cancion-de-la-semana","tag-electronica","tag-francia","tag-rien-virgule"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=5262"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5262\/revisions"}],"predecessor-version":[{"id":5264,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/5262\/revisions\/5264"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=5262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=5262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=5262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}