{"id":521,"date":"2008-02-13T23:02:00","date_gmt":"2008-02-13T23:02:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=521"},"modified":"2008-02-13T23:02:00","modified_gmt":"2008-02-13T23:02:00","slug":"esa-voz","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/02\/13\/esa-voz\/","title":{"rendered":"Esa voz"},"content":{"rendered":"<p class=\"MsoNormal\"><span>Y bueno, \u00bfhan escuchado a <\/span><a id=\"link_0\" title=\"http:\/\/www.myspace.com\/manosdetopo\" href=\"http:\/\/www.myspace.com\/manosdetopo\" rel=\"external nofollow\">Manos de Topo<\/a><span>? Les pongo en situaci\u00f3n: hay cr\u00edticos por ah\u00ed que escogieron su debut, <\/span><em>Ortopedias bonitas<\/em><span>, como mejor \u00e1lbum del a\u00f1o pasado, y ahora mismo acabo de leer en una rese\u00f1a que \u201csuponen un punto y aparte en el pop en espa\u00f1ol m\u00e1s reciente\u201d y que el histrionismo de su vocalista \u201cprovoca una desasosegante sensaci\u00f3n de cercan\u00eda y complicidad\u201d. Hasta ahora, mi experiencia personal siempre se ha detenido en la parte desasosegante, pero prefiero no condicionarles con mis prejuicios trogloditas y someterlo a su criterio: pinchen abajo y d\u00edganme qu\u00e9 les parece, que yo prometo dejarme influir. Ah, el videoclip es estupendo, de eso cabe poca duda. <\/span><\/p>\n<p><object width=\"425\" height=\"355\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/5n-C8CyCp00&#038;rel=1\" \/><embed width=\"425\" height=\"355\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/5n-C8CyCp00&#038;rel=1\" wmode=\"transparent\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Y bueno, \u00bfhan escuchado a Manos de Topo? Les pongo en situaci\u00f3n: hay cr\u00edticos por ah\u00ed que escogieron su debut, Ortopedias bonitas, como mejor \u00e1lbum del a\u00f1o pasado, y ahora mismo acabo de leer en una rese\u00f1a que \u201csuponen un punto y aparte en el pop en espa\u00f1ol m\u00e1s reciente\u201d y que el histrionismo de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[774,1879,3191],"class_list":["post-521","post","type-post","status-publish","format-standard","hentry","category-musica","tag-discos","tag-manos-de-topo","tag-voces"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=521"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/521\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}