{"id":514,"date":"2008-01-17T13:13:00","date_gmt":"2008-01-17T13:13:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=514"},"modified":"2008-01-17T13:13:00","modified_gmt":"2008-01-17T13:13:00","slug":"imagen-y-semejanza","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2008\/01\/17\/imagen-y-semejanza\/","title":{"rendered":"Imagen y semejanza"},"content":{"rendered":"<p>Mi primo, que es una autoridad tan buena como cualquier otra para empezar un <em>post<\/em>, suele afearme lo arbitrario y, en definitiva, injusto que soy cuando valoro a los grupos de rock que remiten indiscutiblemente a mis favoritos. Y tiene m\u00e1s raz\u00f3n que un santo, por mucho que cada vez le vea m\u00e1s alejado de esa santidad que promet\u00eda en su foto de Primera Comuni\u00f3n. Un d\u00eda desprecio a Interpol porque no ofrecen nada que no estuviese en Joy Division y compa\u00f1\u00eda, y al siguiente estoy escuchando sin descanso a <a id=\"link_1\" title=\"http:\/\/www.myspace.com\/shewantsrevenge\" href=\"http:\/\/www.myspace.com\/shewantsrevenge\" rel=\"external nofollow\">She Wants Revenge<\/a> porque reconozco en ellos, de manera a\u00fan m\u00e1s caricaturesca, la herencia de Joy Division y compa\u00f1\u00eda.<\/p>\n<p>Por mucho que intentemos sustentarlo con argumentos, el gusto tiene un componente arbitrario y, en definitiva, injusto que nos lleva a menudo a la contradicci\u00f3n. Y todo esto viene al caso porque llevo unos cuantos d\u00edas enganchado a <a id=\"link_0\" title=\"http:\/\/www.myspace.com\/aplacetoburystrangers\" href=\"http:\/\/www.myspace.com\/aplacetoburystrangers\" rel=\"external nofollow\">A Place To Bury Strangers<\/a>, banda a la que han saludado por ah\u00ed como \u201cla m\u00e1s ruidosa de Nueva York\u201d pero que se podr\u00eda definir mejor como \u201cla m\u00e1s parecida a Jesus &#038; Mary Chain\u201d, aunque s\u00f3lo los citen en tercer lugar dentro de su listado de referencias. Loop aparecen los cuartos y My Bloody Valentine, los novenos, pero esos vienen a ser los ingredientes fundamentales de su sonido, evidentemente distorsionado y descrito por ellos mismos como \u201cun Tyrannosaurus Rex agonizante\u201d. Tengo debilidad por los grupos con esas referencias, desde Tri\u00e1ngulo de Amor Bizarro a los Psychic Ills, pero reconozco que A Place To Bury Strangers (por cierto, los primeros en la lista alfab\u00e9tica de mi iPod) son los m\u00e1s mim\u00e9ticos del lote. Aportar, aportar, no aportan mucho. Y sin embargo&#8230;<\/p>\n<p><object width=\"425\" height=\"355\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/RR2FsiWQe9Y&#038;rel=1\" \/><embed width=\"425\" height=\"355\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/RR2FsiWQe9Y&#038;rel=1\" wmode=\"transparent\" \/><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mi primo, que es una autoridad tan buena como cualquier otra para empezar un post, suele afearme lo arbitrario y, en definitiva, injusto que soy cuando valoro a los grupos de rock que remiten indiscutiblemente a mis favoritos. Y tiene m\u00e1s raz\u00f3n que un santo, por mucho que cada vez le vea m\u00e1s alejado de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[30,774,2189,2529,2658],"class_list":["post-514","post","type-post","status-publish","format-standard","hentry","category-musica","tag-a-place-to-bury-strangers","tag-discos","tag-nueva-york","tag-rock","tag-she-wants-revenge"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}