{"id":497,"date":"2007-11-14T12:01:00","date_gmt":"2007-11-14T12:01:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=497"},"modified":"2007-11-14T12:01:00","modified_gmt":"2007-11-14T12:01:00","slug":"desanimacion-callejera","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/11\/14\/desanimacion-callejera\/","title":{"rendered":"Desanimaci\u00f3n callejera"},"content":{"rendered":"<p>Soy una de esas personas saludables que pasean los domingos por la ma\u00f1ana, cuando muchos de ustedes se dedican simplemente a exudar toxinas. Suelo caminar con placidez de prejubilado por el centro de Bilbao o por el parque Etxebarria, pero esa rutina apacible se ve arruinada \u00faltimamente por la insidiosa megafon\u00eda, aunque s\u00e9 que esto ha sonado un poco al ilustre compa\u00f1ero <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/20071104\/vizcaya\/pronto-empezamos-20071104.html\" target=\"_blank\" rel=\"external nofollow\">Olmo<\/a>. Por un lado est\u00e1 la pesca infantil en la r\u00eda, que no s\u00e9 por qu\u00e9 diablos ha de tener m\u00fasica de fondo; por otro, las ocasionales competiciones deportivas, que -adem\u00e1s de eso- no s\u00e9 por qu\u00e9 diablos han de discurrir por el cogollo de la villa y no por alg\u00fan pol\u00edgono discreto y apartado. Lo que m\u00e1s me preocupa es lo de la pesca: \u00bftiene sentido que, a la vez que demuestran que el agua se va limpiando, contaminen ac\u00fasticamente buena parte del casco urbano, hasta el parque y m\u00e1s all\u00e1?<\/p>\n<p>Y, para colmo, est\u00e1 lo que ponen. S\u00f3lo artistas vascos, vale. S\u00f3lo artistas vascos que canten en euskera, mmmm&#8230; S\u00f3lo artistas vascos que canten en euskera y con un pie o los dos en el folk&#8230; Pues miren, no, ya basta: \u00a1qu\u00e9 pesadez que se identifique la animaci\u00f3n callejera con esas canciones o\u00eddas mil veces! \u00a1Aburre hasta a los peces! Y perdonen que les diga, porque supongo que el criterio del DJ ser\u00e1 ideol\u00f3gico: \u00a1qu\u00e9 sensaci\u00f3n de cultura muerta! Da la impresi\u00f3n de que quieren ocultar a los ni\u00f1os que existe la diversidad, incluso aqu\u00ed, y que se puede ser la persona m\u00e1s vasca del mundo sin necesidad de escuchar todas las fiestas de guardar <em>Euskal Herrian euskaraz<\/em>. En fin, me imagino que jam\u00e1s van a pinchar flamenquito -por mucho que Ojos de Brujo toquen en el Ikasle Eguna-, pero pod\u00edan colar un par\u00e9ntesis internacionalista de Vivaldi o Bach entre Oskorri y Sorotan Bele, o al menos descubrir que Euskadi sigue produciendo artistas aptos para las ma\u00f1anas como, y digo los primeros que se me ocurren, Tulsa, Rubia, Chico y Chica, <a href=\"http:\/\/www.icoppel.com\/\" target=\"_blank\" rel=\"external nofollow\">I\u00f1igo Coppel<\/a> o El Ment\u00f3n de Fogarty.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Soy una de esas personas saludables que pasean los domingos por la ma\u00f1ana, cuando muchos de ustedes se dedican simplemente a exudar toxinas. Suelo caminar con placidez de prejubilado por el centro de Bilbao o por el parque Etxebarria, pero esa rutina apacible se ve arruinada \u00faltimamente por la insidiosa megafon\u00eda, aunque s\u00e9 que esto [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,7],"tags":[327,1304,2085],"class_list":["post-497","post","type-post","status-publish","format-standard","hentry","category-inclasificables","category-musica","tag-bilbao","tag-horrores","tag-musica-vasca"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}