{"id":4954,"date":"2020-07-17T10:40:22","date_gmt":"2020-07-17T09:40:22","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4954"},"modified":"2020-07-17T10:40:37","modified_gmt":"2020-07-17T09:40:37","slug":"cancion-de-la-semana-fundo-de-mare-palinha","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2020\/07\/17\/cancion-de-la-semana-fundo-de-mare-palinha\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Fundo de mar\u00ea palinha&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4955\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau-600x352.jpg\" alt=\"\" width=\"559\" height=\"328\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau-600x352.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau-150x88.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau-300x176.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau-768x450.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2020\/07\/Voz-di-Sanicolau.jpg 1276w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Unos m\u00e1s y otros menos, pero al final todos solemos incurrir en cierta medida en el vicio de hozar en nuestro nicho estil\u00edstico favorito y perdernos un amplio espectro de la m\u00fasica que queda fuera de \u00e9l. Yo qu\u00e9 s\u00e9, dedicamos el tiempo a escuchar un disco de post-punk que es exactamente igual a otros dos mil discos de post-punk (pongo el ejemplo que m\u00e1s puede tocarme a m\u00ed, pero lo mismo vale para la Americana, el black metal o cualquier subg\u00e9nero o infrag\u00e9nero que se les ocurra) y no prestamos atenci\u00f3n a infinidad de propuestas que consideramos ajenas a nuestros gustos. Por fortuna, de vez en cuando llega esa canci\u00f3n fresca y estimulante que nos hace conscientes de nuestra propia cerraz\u00f3n e incluso nos lleva a cuestionarnos nuestros h\u00e1bitos de escucha: pues bien, la \u00faltima que ha obrado en m\u00ed ese efecto tan saludable es nuestra canci\u00f3n de esta semana, <em>Fundo de mar\u00ea palinha<\/em>, y puedo decir que el entusiasmo se ha contagiado a mi familia. No ha hecho falta mucho empe\u00f1o, porque ya acabaron cant\u00e1ndola LA PRIMERA VEZ que la oyeron.<\/p>\n<p><em>Fundo de mar\u00ea palinha<\/em> da t\u00edtulo y abre el \u00fanico disco de Voz di Sanicolau, un septeto de Cabo Verde (concretamente, claro, de la isla de Sanicolau o S\u00e3o Nicolau) que solo dej\u00f3 un legado de seis canciones registradas. Las grabaron en 1976 en Rotterdam, destino habitual de la di\u00e1spora caboverdiana, pero la vida se impuso, qu\u00e9 antip\u00e1tica, y los miembros de la banda tuvieron que volver a sus trabajos en lugar de perseguir las fantas\u00edas del \u00e9xito. Ahora, el imprescindible sello <a href=\"https:\/\/analogafrica.com\/\" rel=\"external nofollow\">Analog Africa<\/a> recupera del olvido estas seis canciones efervescentes, trepidantes y a la vez impregnadas de esa melancol\u00eda de fondo que la mayor\u00eda conocimos a trav\u00e9s de Ces\u00e1ria \u00c9vora. Lo que hacen Voz di Sanicolau es coladeira, una suerte de versi\u00f3n acelerada de la morna, con una instrumentaci\u00f3n que combina las guitarras el\u00e9ctricas y el peque\u00f1o cavaquinho portugu\u00e9s y con dos vocalistas (Joana do Rosario y T\u00f4-Z\u00e9) a los que esta peque\u00f1a eternidad transcurrida no ha restado un \u00e1pice de su fuerza. Abran la puerta del nicho, vent\u00edlenlo un poco y canten (bueno, tarareen) con nosotros este derroche r\u00edtmico y mel\u00f3dico.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=4258955140\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=2487735499\/transparent=true\/\" seamless=\"\"><a href=\"http:\/\/analogafrica.bandcamp.com\/album\/fundo-de-mar-palinha-limited-dance-edition\" rel=\"external nofollow\">Fundo De Mar\u00ea Palinha (Limited Dance Edition) by Voz di Sanicolau<\/a><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Unos m\u00e1s y otros menos, pero al final todos solemos incurrir en cierta medida en el vicio de hozar en nuestro nicho estil\u00edstico favorito y perdernos un amplio espectro de la m\u00fasica que queda fuera de \u00e9l. Yo qu\u00e9 s\u00e9, dedicamos el tiempo a escuchar un disco de post-punk que es exactamente igual a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[66,3797,165,3795,461,2486,3796],"class_list":["post-4954","post","type-post","status-publish","format-standard","hentry","category-musica","tag-africa","tag-analog-africa","tag-anos-70","tag-cabo-verde","tag-cancion-de-la-semana","tag-reediciones","tag-voz-di-sanicolau"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4954"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4954\/revisions"}],"predecessor-version":[{"id":4957,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4954\/revisions\/4957"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}