{"id":469,"date":"2007-09-08T11:23:00","date_gmt":"2007-09-08T11:23:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/evadidos\/?p=468"},"modified":"2007-09-08T11:23:00","modified_gmt":"2007-09-08T11:23:00","slug":"gente-extrana","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2007\/09\/08\/gente-extrana\/","title":{"rendered":"Gente extra\u00f1a"},"content":{"rendered":"<p>El rock es una m\u00e1quina portentosa de generar personajes. Claro, no es lo mismo trabajar en una caja de ahorros que ser guitarrista en un grupo: lo primero siempre obliga a rebajar un poco las aristas de la propia personalidad para encajar en el mismo molde que todos los dem\u00e1s, por mucho que se mantenga alguna excentricidad privada para seguir sinti\u00e9ndose vivo, pero el rock como profesi\u00f3n estimula la rareza y convierte a j\u00f3venes inadaptados en adultos marcianos. Lo pensaba ayer leyendo el n\u00famero de septiembre de <a href=\"http:\/\/www.google.es\/url?sa=t&#038;ct=res&#038;cd=1&#038;url=http%3A%2F%2Fwww.uncut.co.uk%2F&#038;ei=mGniRpHZGJj8wwHmqtTXDA&#038;usg=AFQjCNEDsrb3OdjPXXWTUtf8TkIBugcahQ&#038;sig2=cjmy91JmTfIEYy53wBiwOA\" target=\"_blank\" rel=\"external nofollow\"><em>Uncut<\/em><\/a>, una revista brit\u00e1nica que siempre reserva la portada para alguna vaca sagrada -ya saben, artistas <em>historiqu\u00edsimos <\/em>como Hendrix o los Beatles- pero que tambi\u00e9n hace gala de un marcado inter\u00e9s por los comportamientos bizarros y los excesos m\u00e1s desparramados.<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/evadidos\/2007\/09\/08\/gente-extrana\/cope\/\" rel=\"attachment wp-att-2159\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-2159\" title=\"Julian Cope\" src=\"\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/09\/Cope.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/09\/Cope.jpg 400w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/09\/Cope-113x150.jpg 113w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2007\/09\/Cope-225x300.jpg 225w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>No me resisto a resumirles los perfiles de algunos m\u00fasicos que aparecen en este n\u00famero y sus declaraciones m\u00e1s curiosas o incorrectas. El se\u00f1or de la foto, <a href=\"http:\/\/www.youtube.com\/watch?v=amJdDRWbX-0\" target=\"_blank\" rel=\"external nofollow\">Julian Cope<\/a> (peculiaridad extramusical m\u00e1s destacada: su obsesi\u00f3n por el paganismo, que le lleva a disertar sobre dioses n\u00f3rdicos y megalitos y a retratarse vestido de druida), habla sobre sus compa\u00f1eros de anta\u00f1o en el grupo The Teardrop Explodes: &#8220;No les perdonar\u00eda, pero, como persona con un enfoque vikingo de la vida, me encantar\u00eda poder pasar a los tres por el garrote y ejecutarlos sumariamente en alg\u00fan cenagal dan\u00e9s en honor a Frigga o Freya&#8221;. El inquietante <a href=\"http:\/\/www.youtube.com\/watch?v=DraXtCmWs0w\" target=\"_blank\" rel=\"external nofollow\">Genesis P-Orridge<\/a> (peculiaridad extramusical m\u00e1s destacada: sus implantes mamarios) repasa su biograf\u00eda en fotos: &#8220;En parte, es el \u00e1ngulo de c\u00e1mara lo que hace que mis pechos parezcan tan grandes, aunque est\u00e1n todav\u00eda hinchados por la cirug\u00eda. Ense\u00f1arlos es un truco deliberado por mi parte para mostrar al resto de la banda qu\u00e9 predecibles son los fot\u00f3grafos masculinos&#8221;. <a href=\"http:\/\/theheroindiaries.net\/\" target=\"_blank\" rel=\"external nofollow\">Nikki Sixx<\/a>, bajista de M\u00f6tley Cr\u00fce (peculiaridad extramusical m\u00e1s destacada: sus drogas y sus mujeres, todo ello por v\u00eda genital), responde a una pregunta cl\u00e1sica en la revista: \u00bfcoger\u00edas un malet\u00edn con 500 millones de d\u00f3lares si supieses que, al hacerlo, un chino se iba a caer de su bici en Pek\u00edn y se iba a matar? &#8220;Parece que podr\u00eda ayudar a la gente si me llevase el malet\u00edn y gastase el dinero en caridad. \u00bfTiene que ser chino? Si podemos hacer que sea un franc\u00e9s hijo de puta, coger\u00e9 el malet\u00edn. Me lo llevar\u00e9 bailando&#8221;. Y, finalmente, el egregio <a href=\"http:\/\/blogs.elcorreo.com\/index.php\/evadidos\/2006\/09\/21\/\" target=\"_blank\">Robert Wyatt<\/a> (peculiaridad extramusical m\u00e1s destacada: se qued\u00f3 parapl\u00e9jico al caerse por una ventana, borracho, durante una fiesta) se explaya sobre su afici\u00f3n al tabaco: &#8220;La gente me pregunta cu\u00e1nto fumo y yo respondo que tanto como me resulta posible. Si existiese un cigarrillo de una milla que pudiese sostener en la boca, me lo meter\u00eda por la ma\u00f1ana y no lo sacar\u00eda hasta la noche&#8221;. Y, ya ven, todos ellos han hecho buena m\u00fasica en alg\u00fan momento de sus extra\u00f1as vidas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El rock es una m\u00e1quina portentosa de generar personajes. Claro, no es lo mismo trabajar en una caja de ahorros que ser guitarrista en un grupo: lo primero siempre obliga a rebajar un poco las aristas de la propia personalidad para encajar en el mismo molde que todos los dem\u00e1s, por mucho que se mantenga [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[660,1125,1532,1702,2149,2524,3132],"class_list":["post-469","post","type-post","status-publish","format-standard","hentry","category-musica","tag-curiosidades","tag-genesis-p-orridge","tag-julian-cope","tag-lecturas","tag-nikki-sixx","tag-robert-wyatt","tag-uncut"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=469"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/469\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}