{"id":4607,"date":"2019-10-11T16:57:18","date_gmt":"2019-10-11T15:57:18","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/evadidos\/?p=4607"},"modified":"2019-10-11T16:57:51","modified_gmt":"2019-10-11T15:57:51","slug":"cancion-de-la-semana-dance-alone","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/evadidos\/2019\/10\/11\/cancion-de-la-semana-dance-alone\/","title":{"rendered":"Canci\u00f3n de la semana: &#8216;Dance Alone&#8217;"},"content":{"rendered":"<div id=\"attachment_4608\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4608\" class=\" wp-image-4608\" src=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans-600x341.jpg\" alt=\"\" width=\"560\" height=\"318\" srcset=\"https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans-600x341.jpg 600w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans-150x85.jpg 150w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans-300x171.jpg 300w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans-768x437.jpg 768w, https:\/\/blogs.elcorreo.com\/evadidos\/wp-content\/uploads\/sites\/2\/2019\/10\/Shari-Vari-foto-Tom-Otte-Willy-Hans.jpg 1677w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><p id=\"caption-attachment-4608\" class=\"wp-caption-text\"><em>Foto: Tom Otte\/Willy Hans<\/em><\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Cada vez que leo el nombre del d\u00fao hamburgu\u00e9s <a href=\"https:\/\/www.facebook.com\/sharivarimusic\/\" rel=\"external nofollow\">Shari Vari<\/a>, brota en mi cabeza el recuerdo de la pret\u00e9rita tienda de discos pamplonesa Xaribari, y yo pensaba que era un simple efecto tonto de yuxtaposici\u00f3n en la memoria, pero acabo de indagar un poquito y a lo mejor hasta tiene su l\u00f3gica. Me imagino que Shari Vari se han puesto ese nombre en honor de la canci\u00f3n <em>Shari Vari<\/em>, de A Number Of Names, conocida tambi\u00e9n como <em>Sharevari<\/em> y un cl\u00e1sico de prototechno de Detroit. Y, puesto a suponer, parece probable que el t\u00edtulo de ese tena venga del franc\u00e9s <em>charivari<\/em>, es decir, jaleo, guirigay, lo mismo que <em>xaribari<\/em> en euskera.<\/p>\n<p>Ya disculpar\u00e1n la digresi\u00f3n, pero es que me ha hecho gracia la cosa. Lo de la relaci\u00f3n con <a href=\"https:\/\/www.youtube.com\/watch?v=huofr2_h8dI\" rel=\"external nofollow\">la canci\u00f3n ochentera de marras<\/a> parece bastante probable, sobre todo a juzgar por las bases de <em>Dance Alone<\/em>, aunque a m\u00ed el nombre que se me viene inmediatamente a la cabeza en cuanto empiezo a escucharla es Suicide. Y, la verdad, me suelen encantar todas las canciones que me traen a Suicide a la cabeza. Esa influencia ya no es solo una suposici\u00f3n m\u00eda, porque la tercera y la cuarta palabras de la nota de prensa de Shari Vari son Alan y Vega, en la frase \u00abcomo si Alan Vega llevase gafas de sol rosas\u00bb.<\/p>\n<p>Y dejo ya de dar vueltas para explicar que Shari Vari son las artistas Sophia Kennedy y Helena Ratka, que su grupo musical naci\u00f3 a partir de una exposici\u00f3n conjunta sobre una <em>superstar<\/em> imaginaria y que me encantan sus canciones con herencia de Suicide y cierto fondo industrial, pero a la vez resultonas y bailables. Es, de hecho, ese tipo de m\u00fasica que me gustar\u00eda bailar en los clubes si alguna vez bailase en los clubes. Y encima tiene v\u00eddeo chulo y extra\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/LycHQS-0FZw\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Cada vez que leo el nombre del d\u00fao hamburgu\u00e9s Shari Vari, brota en mi cabeza el recuerdo de la pret\u00e9rita tienda de discos pamplonesa Xaribari, y yo pensaba que era un simple efecto tonto de yuxtaposici\u00f3n en la memoria, pero acabo de indagar un poquito y a lo mejor hasta tiene su l\u00f3gica. Me [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[99,461,3710],"class_list":["post-4607","post","type-post","status-publish","format-standard","hentry","category-musica","tag-alemania","tag-cancion-de-la-semana","tag-shari-vari"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/comments?post=4607"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4607\/revisions"}],"predecessor-version":[{"id":4611,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/posts\/4607\/revisions\/4611"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/media?parent=4607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/categories?post=4607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/evadidos\/wp-json\/wp\/v2\/tags?post=4607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}